{"id":111365,"date":"2019-09-01T05:18:40","date_gmt":"2019-09-01T05:18:40","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-malasia-en-lieja-belgica\/"},"modified":"2019-09-01T05:18:40","modified_gmt":"2019-09-01T05:18:40","slug":"consulado-de-malasia-en-lieja-belgica","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-malasia-en-lieja-belgica\/","title":{"rendered":"Consulado de Malasia en Lieja, B\u00e9lgica"},"content":{"rendered":"<div id=\"trave-3163435541\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado de Malasia en Liege, B\u00e9lgica<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nRue des Renards 4<br \/>\n4130 Tilff (Esneux)<br \/>\nB\u00e9lgica<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Jean-Claude Havaux, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+32) 4 368 66 56<br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong> jc.havaux@zentech.be<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-4240889821\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado de Malasia en Liege, B\u00e9lgica Direcci\u00f3n: Rue des Renards 4 4130 Tilff (Esneux) B\u00e9lgica Embajador: Jean-Claude Havaux, C\u00f3nsul Honorario Tel\u00e9fono: (+32) 4 368 66 56 Fax: Email: jc.havaux@zentech.be Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13141,13291,13867,13290],"tags":[12978],"class_list":["post-111365","post","type-post","status-publish","format-standard","hentry","category-belgica","category-consulados-de-malasia","category-consulados-en-belgica","category-malasia","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/111365"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=111365"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/111365\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=111365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=111365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=111365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}