{"id":111234,"date":"2019-09-01T05:17:24","date_gmt":"2019-09-01T05:17:24","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-finlandia-en-bridgetown-barbados\/"},"modified":"2019-09-01T05:17:24","modified_gmt":"2019-09-01T05:17:24","slug":"consulado-general-de-finlandia-en-bridgetown-barbados","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-finlandia-en-bridgetown-barbados\/","title":{"rendered":"Consulado General de Finlandia en Bridgetown, Barbados"},"content":{"rendered":"<div id=\"trave-3769086118\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado finland\u00e9s en Bridgetown, Barbados<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nTrident Insurance Financial Center<br \/>\nHighway 7<br \/>\nHastings<br \/>\nChrist Church<br \/>\nBarbados<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Algernon Leacock, C\u00f3nsul General Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+1 246) 431 2347<br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong> stepneys@caribsurf.com<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-2401687381\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado finland\u00e9s en Bridgetown, Barbados Direcci\u00f3n: Trident Insurance Financial Center Highway 7 Hastings Christ Church Barbados Embajador: Mr Algernon Leacock, C\u00f3nsul General Honorario Tel\u00e9fono: (+1 246) 431 2347 Fax: Email: stepneys@caribsurf.com Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4906,13854,13652,12998],"tags":[12988],"class_list":["post-111234","post","type-post","status-publish","format-standard","hentry","category-barbados","category-consulado-general-en-barbados","category-consulado-general-finlandes","category-finlandia","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/111234"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=111234"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/111234\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=111234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=111234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=111234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}