{"id":111230,"date":"2019-09-01T05:17:22","date_gmt":"2019-09-01T05:17:22","guid":{"rendered":"https:\/\/travelqa.com\/alta-comision-de-canada-en-bridgetown-barbados\/"},"modified":"2019-09-01T05:17:22","modified_gmt":"2019-09-01T05:17:22","slug":"alta-comision-de-canada-en-bridgetown-barbados","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/alta-comision-de-canada-en-bridgetown-barbados\/","title":{"rendered":"Alta Comisi\u00f3n de Canad\u00e1 en Bridgetown, Barbados"},"content":{"rendered":"<div id=\"trave-3968568282\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles de la Alta Comisi\u00f3n Canadiense en Bridgetown, Barbados<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nPO Box 404<br \/>\nBridgetown<br \/>\nBarbados<br \/>\n<strong><br \/>\nEmbajador:<\/strong><br \/>\n<strong>Tel\u00e9fono:<\/strong> (+1 246) 429 3550<br \/>\n<strong>Fax:<\/strong> (+1 246) 429 3780<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> www.canadainternational.gc.ca\/barbados-barbade\/<\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-1597122447\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles de la Alta Comisi\u00f3n Canadiense en Bridgetown, Barbados Direcci\u00f3n: PO Box 404 Bridgetown Barbados Embajador: Tel\u00e9fono: (+1 246) 429 3550 Fax: (+1 246) 429 3780 Email: Sitio web: www.canadainternational.gc.ca\/barbados-barbade\/ Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13641,13855,4906,5085],"tags":[13640],"class_list":["post-111230","post","type-post","status-publish","format-standard","hentry","category-altas-comisiones-canadienses","category-altas-comisiones-en-barbados","category-barbados","category-canada","tag-alta-comision"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/111230"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=111230"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/111230\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=111230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=111230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=111230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}