{"id":111229,"date":"2019-09-01T05:17:22","date_gmt":"2019-09-01T05:17:22","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-luxemburgo-en-bridgetown-barbados\/"},"modified":"2019-09-01T05:17:22","modified_gmt":"2019-09-01T05:17:22","slug":"consulado-general-de-luxemburgo-en-bridgetown-barbados","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-luxemburgo-en-bridgetown-barbados\/","title":{"rendered":"Consulado General de Luxemburgo en Bridgetown, Barbados"},"content":{"rendered":"<div id=\"trave-4102047466\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Luxemburgo en Bridgetown, Barbados<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n117 Port St.<br \/>\nSanCarlosPeter<br \/>\nBarbados<br \/>\n<strong><br \/>\nEmbajador:<\/strong><br \/>\n<strong>Tel\u00e9fono:<\/strong> (+1 246) 419-1260<br \/>\n(+1 246) 419-1117<br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-1784574787\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Luxemburgo en Bridgetown, Barbados Direcci\u00f3n: 117 Port St. SanCarlosPeter Barbados Embajador: Tel\u00e9fono: (+1 246) 419-1260 (+1 246) 419-1117 Fax: Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4906,13637,13854,13474],"tags":[12988],"class_list":["post-111229","post","type-post","status-publish","format-standard","hentry","category-barbados","category-consulado-general-de-luxemburgo","category-consulado-general-en-barbados","category-luxemburgo","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/111229"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=111229"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/111229\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=111229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=111229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=111229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}