{"id":111161,"date":"2019-09-01T05:16:41","date_gmt":"2019-09-01T05:16:41","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-grecia-en-dacca-bangladesh\/"},"modified":"2019-09-01T05:16:41","modified_gmt":"2019-09-01T05:16:41","slug":"consulado-de-grecia-en-dacca-bangladesh","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-grecia-en-dacca-bangladesh\/","title":{"rendered":"Consulado de Grecia en Dacca, Bangladesh"},"content":{"rendered":"<div id=\"trave-3201434239\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado griego en Dacca, Bangladesh<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nc \/ o Reliance Insurance Ltd., 11 \u00b0 piso<br \/>\n8 Rajuk Avenue<br \/>\nDhaka 1000<br \/>\nBangladesh<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Anwarul Huq, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+880) 2 955 7220<br \/>\n(+880) 2 956 7825<br \/>\n<strong>Fax:<\/strong> (+880) 2 956 3297<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-961756314\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado griego en Dacca, Bangladesh Direcci\u00f3n: c \/ o Reliance Insurance Ltd., 11 \u00b0 piso 8 Rajuk Avenue Dhaka 1000 Bangladesh Embajador: Anwarul Huq, C\u00f3nsul Honorario Tel\u00e9fono: (+880) 2 955 7220 (+880) 2 956 7825 Fax: (+880) 2 956 3297 Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4892,13833,13492,13238],"tags":[12978],"class_list":["post-111161","post","type-post","status-publish","format-standard","hentry","category-bangladesh","category-consulados-en-bangladesh","category-consulados-griegos","category-grecia","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/111161"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=111161"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/111161\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=111161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=111161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=111161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}