{"id":111023,"date":"2019-09-01T05:15:21","date_gmt":"2019-09-01T05:15:21","guid":{"rendered":"https:\/\/travelqa.com\/embajada-de-costa-rica-en-baku-azerbaiyan\/"},"modified":"2019-09-01T05:15:21","modified_gmt":"2019-09-01T05:15:21","slug":"embajada-de-costa-rica-en-baku-azerbaiyan","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/embajada-de-costa-rica-en-baku-azerbaiyan\/","title":{"rendered":"Embajada de Costa Rica en Bak\u00fa, Azerbaiy\u00e1n"},"content":{"rendered":"<div id=\"trave-4001276639\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles de la Embajada de Costa Rica en Bak\u00fa, Azerbaiy\u00e1n<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nBak\u00fa 1010<br \/>\nAzerbaiy\u00e1n<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Sr. Jairo Francisco L\u00f3pez Bola\u00f1os, Encargado de Negocios ai<br \/>\n<strong>Tel\u00e9fono:<\/strong><br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-3328651653\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles de la Embajada de Costa Rica en Bak\u00fa, Azerbaiy\u00e1n Direcci\u00f3n: Bak\u00fa 1010 Azerbaiy\u00e1n Embajador: Sr. Jairo Francisco L\u00f3pez Bola\u00f1os, Encargado de Negocios ai Tel\u00e9fono: Fax: Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13332,5199,13547,13812],"tags":[12975],"class_list":["post-111023","post","type-post","status-publish","format-standard","hentry","category-azerbaiyan","category-costa-rica","category-embajadas-costarricenses","category-embajadas-en-azerbaiyan","tag-embajada"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/111023"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=111023"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/111023\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=111023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=111023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=111023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}