{"id":110795,"date":"2019-09-01T05:12:37","date_gmt":"2019-09-01T05:12:37","guid":{"rendered":"https:\/\/travelqa.com\/nunciatura-apostolica-de-la-santa-sede-en-viena-austria\/"},"modified":"2019-09-01T05:12:37","modified_gmt":"2019-09-01T05:12:37","slug":"nunciatura-apostolica-de-la-santa-sede-en-viena-austria","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/nunciatura-apostolica-de-la-santa-sede-en-viena-austria\/","title":{"rendered":"Nunciatura Apost\u00f3lica de la Santa Sede en Viena, Austria"},"content":{"rendered":"<div id=\"trave-2538239965\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles de la Nunciatura Apost\u00f3lica de la Santa Sede en Viena, Austria<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nTheresianumgasse 31<br \/>\n1040 Wien<br \/>\nAustria<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Arzobispo Peter Stephan Zurbriggen, Nuncio Apost\u00f3lico<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+43) (1) 505 13 27<br \/>\n<strong>Fax:<\/strong> (+43) (1) 505 61 40<br \/>\n<strong>Email:<\/strong> nuntius@nuntiatur.at<br \/>\n<strong>Sitio web:<\/strong> www.nuntiatur.at<\/p>\n<p><strong>Horas de oficina:<\/strong> 09.00 &#8211; 13.00 y 15.00 &#8211; 17.00<\/p>\n<div id=\"trave-2033530596\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles de la Nunciatura Apost\u00f3lica de la Santa Sede en Viena, Austria Direcci\u00f3n: Theresianumgasse 31 1040 Wien Austria Embajador: Arzobispo Peter Stephan Zurbriggen, Nuncio Apost\u00f3lico Tel\u00e9fono: (+43) (1) 505 13 27 Fax: (+43) (1) 505 61 40 Email: nuntius@nuntiatur.at Sitio web: www.nuntiatur.at Horas de oficina: 09.00 &#8211; 13.00 y 15.00 &#8211; 17.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4857,13791,13258,13260],"tags":[13262],"class_list":["post-110795","post","type-post","status-publish","format-standard","hentry","category-austria","category-nunciatura-apostolica-en-austria","category-santa-sede","category-santa-sede-nunciatura-apostolica","tag-nunciatura-apostolica"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/110795"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=110795"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/110795\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=110795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=110795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=110795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}