{"id":110538,"date":"2019-09-01T05:09:10","date_gmt":"2019-09-01T05:09:10","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-brasil-en-adelaida-australia\/"},"modified":"2019-09-01T05:09:10","modified_gmt":"2019-09-01T05:09:10","slug":"consulado-de-brasil-en-adelaida-australia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-brasil-en-adelaida-australia\/","title":{"rendered":"Consulado de Brasil en Adelaida, Australia"},"content":{"rendered":"<div id=\"trave-3558291799\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado brasile\u00f1o en Adelaida, Australia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\n40A Kent Street<br \/>\nHawthorn, SA 5062<br \/>\nAustralia<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Peter John McMillan, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+61) 4 1773 3900<br \/>\n<strong>Fax:<\/strong> (+61) 8 8172 1032<br \/>\n<strong>Email:<\/strong> consbrasilsa@gmail.com<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> Con cita<\/p>\n<div id=\"trave-1538620020\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado brasile\u00f1o en Adelaida, Australia Direcci\u00f3n: 40A Kent Street Hawthorn, SA 5062 Australia Embajador: Mr Peter John McMillan, C\u00f3nsul Honorario Tel\u00e9fono: (+61) 4 1773 3900 Fax: (+61) 8 8172 1032 Email: consbrasilsa@gmail.com Sitio web: Horas de oficina: Con cita<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4842,13130,13131,13631],"tags":[12978],"class_list":["post-110538","post","type-post","status-publish","format-standard","hentry","category-australia","category-brasil","category-consulados-de-brasil","category-consulados-en-australia","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/110538"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=110538"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/110538\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=110538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=110538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=110538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}