{"id":110457,"date":"2019-09-01T05:08:26","date_gmt":"2019-09-01T05:08:26","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-la-republica-de-corea-en-sydney-australia\/"},"modified":"2019-09-01T05:08:26","modified_gmt":"2019-09-01T05:08:26","slug":"consulado-general-de-la-republica-de-corea-en-sydney-australia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-la-republica-de-corea-en-sydney-australia\/","title":{"rendered":"Consulado General de la Rep\u00fablica de Corea en Sydney, Australia"},"content":{"rendered":"<div id=\"trave-848344582\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Corea del Sur en Sydney, Australia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nNivel 10, 44 Market Street<br \/>\nSydney, NSW 2000<br \/>\nAustralia<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Mr Sangsoo Yoon, C\u00f3nsul General<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+61) 2 9210 0200<br \/>\n<strong>Fax:<\/strong> (+61) 2 9210 0202<br \/>\n<strong>Email:<\/strong> consyd@mofa.go.kr<br \/>\n<strong>Sitio web:<\/strong> aus-sydney.mofa.go.kr<\/p>\n<p><strong>Horas de oficina:<\/strong> 09: 00-12: 00 y 13: 00-17: 00<\/p>\n<div id=\"trave-1600468023\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Corea del Sur en Sydney, Australia Direcci\u00f3n: Nivel 10, 44 Market Street Sydney, NSW 2000 Australia Embajador: Mr Sangsoo Yoon, C\u00f3nsul General Tel\u00e9fono: (+61) 2 9210 0200 Fax: (+61) 2 9210 0202 Email: consyd@mofa.go.kr Sitio web: aus-sydney.mofa.go.kr Horas de oficina: 09: 00-12: 00 y 13: 00-17: 00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4842,13619,13632,13151],"tags":[12988],"class_list":["post-110457","post","type-post","status-publish","format-standard","hentry","category-australia","category-consulado-general-de-corea-del-sur","category-consulado-general-en-australia","category-corea-del-sur-republica-de","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/110457"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=110457"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/110457\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=110457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=110457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=110457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}