{"id":110202,"date":"2019-09-01T05:05:50","date_gmt":"2019-09-01T05:05:50","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-nueva-zelanda-en-sydney-australia\/"},"modified":"2019-09-01T05:05:50","modified_gmt":"2019-09-01T05:05:50","slug":"consulado-general-de-nueva-zelanda-en-sydney-australia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-nueva-zelanda-en-sydney-australia\/","title":{"rendered":"Consulado General de Nueva Zelanda en Sydney, Australia"},"content":{"rendered":"<div id=\"trave-2809011699\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Nueva Zelanda en Sydney, Australia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nSydney, NSW 2000<br \/>\nAustralia<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Billie Rhian Moore, C\u00f3nsul General<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+61) 2 9221 7836<br \/>\n<strong>Fax:<\/strong> (+61) 2 9221 7836<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 09.00 a 12.30 y 13.30 a 16.00<\/p>\n<div id=\"trave-1909173677\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Nueva Zelanda en Sydney, Australia Direcci\u00f3n: Sydney, NSW 2000 Australia Embajador: Billie Rhian Moore, C\u00f3nsul General Tel\u00e9fono: (+61) 2 9221 7836 Fax: (+61) 2 9221 7836 Email: Sitio web: Horas de oficina: 09.00 a 12.30 y 13.30 a 16.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4842,13667,13632,13567],"tags":[12988],"class_list":["post-110202","post","type-post","status-publish","format-standard","hentry","category-australia","category-consulado-general-de-nueva-zelanda","category-consulado-general-en-australia","category-nueva-zelanda","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/110202"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=110202"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/110202\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=110202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=110202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=110202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}