{"id":110184,"date":"2019-09-01T05:05:41","date_gmt":"2019-09-01T05:05:41","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-china-en-sydney-australia\/"},"modified":"2019-09-01T05:05:41","modified_gmt":"2019-09-01T05:05:41","slug":"consulado-general-de-china-en-sydney-australia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-china-en-sydney-australia\/","title":{"rendered":"Consulado General de China en Sydney, Australia"},"content":{"rendered":"<div id=\"trave-2991195017\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del consulado chino en Sydney, Australia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nCamperdown, NSW 2050<br \/>\nAustralia<br \/>\n<strong><br \/>\nEmbajador:<\/strong><br \/>\n<strong>Tel\u00e9fono:<\/strong> (+61) 2 8595 8012<br \/>\n(+61) 2 8595 8002 (Visa)<br \/>\n<strong>Fax:<\/strong> (+61) 2 8595 8011<br \/>\n(+61) 2 8595 8021 (Visa)<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 08.30-12.00 y 14.00-17.00<br \/>\n09.00-12.00 (Visa)<\/p>\n<div id=\"trave-2444805723\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del consulado chino en Sydney, Australia Direcci\u00f3n: Camperdown, NSW 2050 Australia Embajador: Tel\u00e9fono: (+61) 2 8595 8012 (+61) 2 8595 8002 (Visa) Fax: (+61) 2 8595 8011 (+61) 2 8595 8021 (Visa) Email: Sitio web: Horas de oficina: 08.30-12.00 y 14.00-17.00 09.00-12.00 (Visa)<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4842,5145,13658,13632],"tags":[12988],"class_list":["post-110184","post","type-post","status-publish","format-standard","hentry","category-australia","category-china","category-consulado-general-de-china","category-consulado-general-en-australia","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/110184"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=110184"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/110184\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=110184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=110184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=110184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}