{"id":110182,"date":"2019-09-01T05:05:38","date_gmt":"2019-09-01T05:05:38","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-china-en-melbourne-australia\/"},"modified":"2019-09-01T05:05:38","modified_gmt":"2019-09-01T05:05:38","slug":"consulado-general-de-china-en-melbourne-australia","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-china-en-melbourne-australia\/","title":{"rendered":"Consulado General de China en Melbourne, Australia"},"content":{"rendered":"<div id=\"trave-1028072969\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado chino en Melbourne, Australia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nToorak<br \/>\nMelbourne, VIC 3142<br \/>\nAustralia<br \/>\n<strong><br \/>\nEmbajador:<\/strong><br \/>\n<strong>Tel\u00e9fono:<\/strong> (+61) 3 9822 0604<br \/>\n(+61) 3 9804 3683 (Visa)<br \/>\n<strong>Fax:<\/strong> (+61) 3 9822 9566<br \/>\n(+61) 3 9824 6340 (Visa)<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> 08.30-12.30 y 14.30-17.00<br \/>\n09.00-15.00 (Visa)<\/p>\n<div id=\"trave-2905579182\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado chino en Melbourne, Australia Direcci\u00f3n: Toorak Melbourne, VIC 3142 Australia Embajador: Tel\u00e9fono: (+61) 3 9822 0604 (+61) 3 9804 3683 (Visa) Fax: (+61) 3 9822 9566 (+61) 3 9824 6340 (Visa) Email: Sitio web: Horas de oficina: 08.30-12.30 y 14.30-17.00 09.00-15.00 (Visa)<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4842,5145,13658,13632],"tags":[12988],"class_list":["post-110182","post","type-post","status-publish","format-standard","hentry","category-australia","category-china","category-consulado-general-de-china","category-consulado-general-en-australia","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/110182"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=110182"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/110182\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=110182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=110182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=110182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}