{"id":109989,"date":"2019-09-01T05:03:51","date_gmt":"2019-09-01T05:03:51","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-croacia-en-cordoba-argentina\/"},"modified":"2019-09-01T05:03:51","modified_gmt":"2019-09-01T05:03:51","slug":"consulado-de-croacia-en-cordoba-argentina","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-croacia-en-cordoba-argentina\/","title":{"rendered":"Consulado de Croacia en C\u00f3rdoba, Argentina"},"content":{"rendered":"<div id=\"trave-2139308338\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado croata en C\u00f3rdoba, Argentina<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nRicardo Rojas 6759 piso 3 oficina 17<br \/>\nArguello CP 5147<br \/>\nC\u00f3rdoba<br \/>\nArgentina<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Nikola Nakic, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+54) 351 432 3619<br \/>\n(+54) 354 340 1215<br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong> consulcroatacba@arnet.com.ar<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-2693365561\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado croata en C\u00f3rdoba, Argentina Direcci\u00f3n: Ricardo Rojas 6759 piso 3 oficina 17 Arguello CP 5147 C\u00f3rdoba Argentina Embajador: Nikola Nakic, C\u00f3nsul Honorario Tel\u00e9fono: (+54) 351 432 3619 (+54) 354 340 1215 Fax: Email: consulcroatacba@arnet.com.ar Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4815,13600,13540,13174],"tags":[12978],"class_list":["post-109989","post","type-post","status-publish","format-standard","hentry","category-argentina","category-consulados-croatas","category-consulados-en-argentina","category-croacia","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/109989"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=109989"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/109989\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=109989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=109989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=109989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}