{"id":109779,"date":"2019-09-01T05:01:24","date_gmt":"2019-09-01T05:01:24","guid":{"rendered":"https:\/\/travelqa.com\/agencia-consular-de-italia-en-mercedes-argentina\/"},"modified":"2019-09-01T05:01:24","modified_gmt":"2019-09-01T05:01:24","slug":"agencia-consular-de-italia-en-mercedes-argentina","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/agencia-consular-de-italia-en-mercedes-argentina\/","title":{"rendered":"Agencia Consular de Italia en Mercedes, Argentina"},"content":{"rendered":"<div id=\"trave-1576827361\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles de la Agencia Consular Italiana en Mercedes, Argentina<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nCalle 33 N \u00b0 340<br \/>\n6600 Mercedes (Buenos Aires)<br \/>\nArgentina<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Pamela Beatriz Infanti, Agente Consular<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+54) 232 442 40 43<br \/>\n<strong>Fax:<\/strong> (+54) 232 442 40 43<br \/>\n<strong>Email:<\/strong> consmercedes@yahoo.it<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-753818091\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles de la Agencia Consular Italiana en Mercedes, Argentina Direcci\u00f3n: Calle 33 N \u00b0 340 6600 Mercedes (Buenos Aires) Argentina Embajador: Pamela Beatriz Infanti, Agente Consular Tel\u00e9fono: (+54) 232 442 40 43 Fax: (+54) 232 442 40 43 Email: consmercedes@yahoo.it Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13558,13577,4815,13062],"tags":[13532],"class_list":["post-109779","post","type-post","status-publish","format-standard","hentry","category-agencias-consulares-en-argentina","category-agencias-consulares-italianas","category-argentina","category-italia","tag-agencia-consular"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/109779"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=109779"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/109779\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=109779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=109779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=109779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}