{"id":109672,"date":"2019-09-01T05:00:23","date_gmt":"2019-09-01T05:00:23","guid":{"rendered":"https:\/\/travelqa.com\/embajada-de-sudafrica-en-buenos-aires-argentina\/"},"modified":"2019-09-01T05:00:23","modified_gmt":"2019-09-01T05:00:23","slug":"embajada-de-sudafrica-en-buenos-aires-argentina","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/embajada-de-sudafrica-en-buenos-aires-argentina\/","title":{"rendered":"Embajada de Sud\u00e1frica en Buenos Aires, Argentina"},"content":{"rendered":"<div id=\"trave-3254666233\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles de la Embajada de Sud\u00e1frica en Buenos Aires, Argentina<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nBuenos Aires 1058<br \/>\nArgentina<br \/>\n<strong><br \/>\nEmbajador:<\/strong><br \/>\n<strong>Tel\u00e9fono:<\/strong> (+54) 11 4317 2900<br \/>\n<strong>Fax:<\/strong> (+54) 11 4311 9993<br \/>\n(+54) 11 4311 8991<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> Lunes a jueves: 08.15 a 12.30 y 13.15 a 17.15<br \/>\nviernes: 08.15 a 14.15<\/p>\n<div id=\"trave-3022932049\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles de la Embajada de Sud\u00e1frica en Buenos Aires, Argentina Direcci\u00f3n: Buenos Aires 1058 Argentina Embajador: Tel\u00e9fono: (+54) 11 4317 2900 Fax: (+54) 11 4311 9993 (+54) 11 4311 8991 Email: Sitio web: Horas de oficina: Lunes a jueves: 08.15 a 12.30 y 13.15 a 17.15 viernes: 08.15 a 14.15<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4815,13543,13326,13251],"tags":[12975],"class_list":["post-109672","post","type-post","status-publish","format-standard","hentry","category-argentina","category-embajadas-en-argentina","category-embajadas-sudafricanas","category-sudafrica","tag-embajada"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/109672"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=109672"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/109672\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=109672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=109672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=109672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}