{"id":109664,"date":"2019-09-01T05:00:20","date_gmt":"2019-09-01T05:00:20","guid":{"rendered":"https:\/\/travelqa.com\/consulado-de-alemania-en-el-calafate-argentina\/"},"modified":"2019-09-01T05:00:20","modified_gmt":"2019-09-01T05:00:20","slug":"consulado-de-alemania-en-el-calafate-argentina","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-de-alemania-en-el-calafate-argentina\/","title":{"rendered":"Consulado de Alemania en El Calafate, Argentina"},"content":{"rendered":"<div id=\"trave-1012340227\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles del consulado alem\u00e1n en El Calafate, Argentina<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nMarcelo T. de Alvear 2157<br \/>\n9405 El Calafate<br \/>\nArgentina<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Bernd Ferstl, C\u00f3nsul Honorario<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+54) 29 02 49 13 93<br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong> calafate@hk-diplo.de<br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-4179035269\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles del consulado alem\u00e1n en El Calafate, Argentina Direcci\u00f3n: Marcelo T. de Alvear 2157 9405 El Calafate Argentina Embajador: Bernd Ferstl, C\u00f3nsul Honorario Tel\u00e9fono: (+54) 29 02 49 13 93 Fax: Email: calafate@hk-diplo.de Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12990,4815,13480,13540],"tags":[12978],"class_list":["post-109664","post","type-post","status-publish","format-standard","hentry","category-alemania","category-argentina","category-consulados-alemanes","category-consulados-en-argentina","tag-consulado"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/109664"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=109664"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/109664\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=109664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=109664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=109664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}