{"id":109524,"date":"2019-09-01T04:58:17","date_gmt":"2019-09-01T04:58:17","guid":{"rendered":"https:\/\/travelqa.com\/consulado-general-de-mali-en-tamanrasset-argelia-2\/"},"modified":"2019-09-01T04:58:17","modified_gmt":"2019-09-01T04:58:17","slug":"consulado-general-de-mali-en-tamanrasset-argelia-2","status":"publish","type":"post","link":"https:\/\/travelqa.com\/es\/consulado-general-de-mali-en-tamanrasset-argelia-2\/","title":{"rendered":"Consulado General de Mal\u00ed en Tamanrasset, Argelia"},"content":{"rendered":"<div id=\"trave-1712273673\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>Detalles generales del Consulado de Mal\u00ed en Tamanrasset, Argelia<\/h3>\n<p><strong><br \/>\nDirecci\u00f3n:<\/strong><br \/>\nTamanrasset<br \/>\nArgelia<br \/>\n<strong><br \/>\nEmbajador:<\/strong> Abderhamane Galla, C\u00f3nsul General<br \/>\n<strong>Tel\u00e9fono:<\/strong> (+213) 29 34 15 78<br \/>\n<strong>Fax:<\/strong> (+213) 29 34 15 78<br \/>\n(+213) 29 34 45 11<br \/>\n<strong>Email:<\/strong><br \/>\n<strong>Sitio web:<\/strong> <\/p>\n<p><strong>Horas de oficina:<\/strong> <\/p>\n<div id=\"trave-3830134986\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Detalles generales del Consulado de Mal\u00ed en Tamanrasset, Argelia Direcci\u00f3n: Tamanrasset Argelia Embajador: Abderhamane Galla, C\u00f3nsul General Tel\u00e9fono: (+213) 29 34 15 78 Fax: (+213) 29 34 15 78 (+213) 29 34 45 11 Email: Sitio web: Horas de oficina:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13275,13460,13329,5941],"tags":[12988],"class_list":["post-109524","post","type-post","status-publish","format-standard","hentry","category-argelia","category-consulado-general-de-mali","category-consulado-general-en-argelia","category-mali","tag-consulado-general"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/109524"}],"collection":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/comments?post=109524"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/posts\/109524\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/media?parent=109524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/categories?post=109524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/es\/wp-json\/wp\/v2\/tags?post=109524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}