{"id":26455,"date":"2019-04-06T23:06:08","date_gmt":"2019-04-06T23:06:08","guid":{"rendered":"https:\/\/travelqa.com\/consulate-of-france-in-maldonado-uruguay\/"},"modified":"2019-04-06T23:06:08","modified_gmt":"2019-04-06T23:06:08","slug":"consulate-of-france-in-maldonado-uruguay","status":"publish","type":"post","link":"https:\/\/travelqa.com\/bn\/consulate-of-france-in-maldonado-uruguay\/","title":{"rendered":"Consulate of France in Maldonado, Uruguay"},"content":{"rendered":"<div id=\"trave-2726681651\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>French Consulate Details in Maldonado, Uruguay<\/h3>\n<p><strong><br \/>\nAddress:<\/strong><br \/>\nCasa Maman, Laguna de Castillo<br \/>\nP. 2529 M. 192, Club del Lago<br \/>\n20003 Punta Ballena u Hotel CONRAD<br \/>\nRambla Williman, Parada 4, Playa Mansa<br \/>\nPunta del Este<br \/>\nUruguay<br \/>\n<strong><br \/>\nAmbassador:<\/strong> Romuald Chapuy, Honorary Consul<br \/>\n<strong>Phone:<\/strong> (+598) 4257 7116<br \/>\n<strong>Fax:<\/strong><br \/>\n<strong>Email:<\/strong> francaisapunta@gmail.com<br \/>\n<strong>Website:<\/strong> <\/p>\n<p><strong>Office Hours:<\/strong> <\/p>\n<div id=\"trave-203175183\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>French Consulate Details in Maldonado, Uruguay Address: Casa Maman, Laguna de Castillo P. 2529 M. 192, Club del Lago 20003 Punta Ballena u Hotel CONRAD Rambla Williman, Parada 4, Playa Mansa Punta del Este Uruguay Ambassador: Romuald Chapuy, Honorary Consul Phone: (+598) 4257 7116 Fax: Email: francaisapunta@gmail.com Website: Office Hours:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6844,5418,5426,6840],"tags":[6933],"class_list":["post-26455","post","type-post","status-publish","format-standard","hentry","category-consulates-in-uruguay","category-france","category-french-consulates","category-uruguay","tag-consulate"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/bn\/wp-json\/wp\/v2\/posts\/26455"}],"collection":[{"href":"https:\/\/travelqa.com\/bn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/bn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/bn\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/bn\/wp-json\/wp\/v2\/comments?post=26455"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/bn\/wp-json\/wp\/v2\/posts\/26455\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/bn\/wp-json\/wp\/v2\/media?parent=26455"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/bn\/wp-json\/wp\/v2\/categories?post=26455"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/bn\/wp-json\/wp\/v2\/tags?post=26455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}