{"id":157413,"date":"2019-09-01T17:19:12","date_gmt":"2019-09-01T17:19:12","guid":{"rendered":"https:\/\/travelqa.com\/%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%a8%d9%8a%d8%b1%d9%88-%d9%81%d9%8a-%d8%aa%d9%88%d9%86%d8%b3-%d8%a7%d9%84%d8%b9%d8%a7%d8%b5%d9%85%d8%a9\/"},"modified":"2019-09-01T17:19:12","modified_gmt":"2019-09-01T17:19:12","slug":"%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%a8%d9%8a%d8%b1%d9%88-%d9%81%d9%8a-%d8%aa%d9%88%d9%86%d8%b3-%d8%a7%d9%84%d8%b9%d8%a7%d8%b5%d9%85%d8%a9","status":"publish","type":"post","link":"https:\/\/travelqa.com\/ar\/%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%a8%d9%8a%d8%b1%d9%88-%d9%81%d9%8a-%d8%aa%d9%88%d9%86%d8%b3-%d8%a7%d9%84%d8%b9%d8%a7%d8%b5%d9%85%d8%a9\/","title":{"rendered":"\u0642\u0646\u0635\u0644\u064a\u0629 \u0628\u064a\u0631\u0648 \u0641\u064a \u062a\u0648\u0646\u0633 \u0627\u0644\u0639\u0627\u0635\u0645\u0629"},"content":{"rendered":"<div id=\"trave-3536173167\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u0628\u064a\u0631\u0648\u0641\u064a\u0629 \u0641\u064a \u062a\u0648\u0646\u0633 \u060c \u062a\u0648\u0646\u0633<\/h3>\n<p><strong><br \/>\n\u0639\u0646\u0648\u0627\u0646:<\/strong><br \/>\n2023 \u0633\u064a\u062f\u064a \u0641\u062a\u062d \u0627\u0644\u0644\u0647<br \/>\n\u062a\u0648\u0646\u0633<br \/>\n\u062a\u0648\u0646\u0633<br \/>\n<strong><br \/>\n\u0633\u0641\u064a\u0631:<\/strong> \u0627\u0644\u0633\u064a\u062f \u0639\u0632\u0627\u0644\u062f\u064a\u0646 \u0627\u0644\u0631\u064a\u0633 \u060c \u0627\u0644\u0642\u0646\u0635\u0644 \u0627\u0644\u0641\u062e\u0631\u064a<br \/>\n<strong>\u0647\u0627\u062a\u0641:<\/strong> (+216) (71) 390 175<br \/>\n<strong>\u0641\u0627\u0643\u0633:<\/strong> (+216) (71) 390 175<br \/>\n<strong>\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong><br \/>\n<strong>\u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> <\/p>\n<p><strong>\u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/strong> 10: 00-13: 00<\/p>\n<div id=\"trave-2008395992\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u0628\u064a\u0631\u0648\u0641\u064a\u0629 \u0641\u064a \u062a\u0648\u0646\u0633 \u060c \u062a\u0648\u0646\u0633 \u0639\u0646\u0648\u0627\u0646: 2023 \u0633\u064a\u062f\u064a \u0641\u062a\u062d \u0627\u0644\u0644\u0647 \u062a\u0648\u0646\u0633 \u062a\u0648\u0646\u0633 \u0633\u0641\u064a\u0631: \u0627\u0644\u0633\u064a\u062f \u0639\u0632\u0627\u0644\u062f\u064a\u0646 \u0627\u0644\u0631\u064a\u0633 \u060c \u0627\u0644\u0642\u0646\u0635\u0644 \u0627\u0644\u0641\u062e\u0631\u064a \u0647\u0627\u062a\u0641: (+216) (71) 390 175 \u0641\u0627\u0643\u0633: (+216) (71) 390 175 \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a: \u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a: \u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644: 10: 00-13: 00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17021,13405,13205,15417],"tags":[12951],"class_list":["post-157413","post","type-post","status-publish","format-standard","hentry","category-17021","category-13405","category-13205","category-15417","tag-12951"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/157413"}],"collection":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/comments?post=157413"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/157413\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/media?parent=157413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/categories?post=157413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/tags?post=157413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}