{"id":156892,"date":"2019-09-01T17:09:13","date_gmt":"2019-09-01T17:09:13","guid":{"rendered":"https:\/\/travelqa.com\/%d8%a7%d9%84%d9%85%d9%83%d8%aa%d8%a8-%d8%a7%d9%84%d8%aa%d8%ac%d8%a7%d8%b1%d9%8a-%d9%84%d9%84%d9%81%d9%84%d8%a8%d9%8a%d9%86-%d9%81%d9%8a-%d8%aa%d8%a7%d9%8a%d8%aa%d8%b4%d9%88%d9%86%d8%ba-%d8%8c-%d8%aa\/"},"modified":"2019-09-01T17:09:13","modified_gmt":"2019-09-01T17:09:13","slug":"%d8%a7%d9%84%d9%85%d9%83%d8%aa%d8%a8-%d8%a7%d9%84%d8%aa%d8%ac%d8%a7%d8%b1%d9%8a-%d9%84%d9%84%d9%81%d9%84%d8%a8%d9%8a%d9%86-%d9%81%d9%8a-%d8%aa%d8%a7%d9%8a%d8%aa%d8%b4%d9%88%d9%86%d8%ba-%d8%8c-%d8%aa","status":"publish","type":"post","link":"https:\/\/travelqa.com\/ar\/%d8%a7%d9%84%d9%85%d9%83%d8%aa%d8%a8-%d8%a7%d9%84%d8%aa%d8%ac%d8%a7%d8%b1%d9%8a-%d9%84%d9%84%d9%81%d9%84%d8%a8%d9%8a%d9%86-%d9%81%d9%8a-%d8%aa%d8%a7%d9%8a%d8%aa%d8%b4%d9%88%d9%86%d8%ba-%d8%8c-%d8%aa\/","title":{"rendered":"\u0627\u0644\u0645\u0643\u062a\u0628 \u0627\u0644\u062a\u062c\u0627\u0631\u064a \u0644\u0644\u0641\u0644\u0628\u064a\u0646 \u0641\u064a \u062a\u0627\u064a\u062a\u0634\u0648\u0646\u063a \u060c \u062a\u0627\u064a\u0648\u0627\u0646"},"content":{"rendered":"<div id=\"trave-891983713\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>\u062a\u0641\u0627\u0635\u064a\u0644 \u0645\u0643\u062a\u0628 \u0627\u0644\u062a\u062c\u0627\u0631\u0629 \u0627\u0644\u0641\u0644\u0628\u064a\u0646\u064a\u0629 \u0641\u064a \u062a\u0627\u064a\u0634\u0648\u0646\u062c \u060c \u062a\u0627\u064a\u0648\u0627\u0646<\/h3>\n<p><strong><br \/>\n\u0639\u0646\u0648\u0627\u0646:<\/strong><br \/>\n\u0631\u0642\u0645 4F-2A239 Min Chuan Road<br \/>\nCor.\u062a\u0627\u064a\u062a\u0634\u0648\u0646\u063a \u0639\u0635\u0627\u0628\u0629 \u0627\u0644\u0637\u0631\u064a\u0642<br \/>\n\u0643\u0627\u062b\u064a \u0627\u0644\u062a\u0623\u0645\u064a\u0646 \u0628\u0646\u0627\u0621<br \/>\n\u062a\u0627\u064a\u062a\u0634\u0648\u0646\u063a<br \/>\n\u062a\u0627\u064a\u0648\u0627\u0646<br \/>\n<strong><br \/>\n\u0633\u0641\u064a\u0631:<\/strong><br \/>\n<strong>\u0647\u0627\u062a\u0641:<\/strong> (+886) 4-2302-9080 to 1<br \/>\n<strong>\u0641\u0627\u0643\u0633:<\/strong> (+886) 4-2229-5900<br \/>\n<strong>\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong><br \/>\n<strong>\u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> www.meco.org.tw<\/p>\n<p><strong>\u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/strong> <\/p>\n<div id=\"trave-2432638089\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u062a\u0641\u0627\u0635\u064a\u0644 \u0645\u0643\u062a\u0628 \u0627\u0644\u062a\u062c\u0627\u0631\u0629 \u0627\u0644\u0641\u0644\u0628\u064a\u0646\u064a\u0629 \u0641\u064a \u062a\u0627\u064a\u0634\u0648\u0646\u062c \u060c \u062a\u0627\u064a\u0648\u0627\u0646 \u0639\u0646\u0648\u0627\u0646: \u0631\u0642\u0645 4F-2A239 Min Chuan Road Cor.\u062a\u0627\u064a\u062a\u0634\u0648\u0646\u063a \u0639\u0635\u0627\u0628\u0629 \u0627\u0644\u0637\u0631\u064a\u0642 \u0643\u0627\u062b\u064a \u0627\u0644\u062a\u0623\u0645\u064a\u0646 \u0628\u0646\u0627\u0621 \u062a\u0627\u064a\u062a\u0634\u0648\u0646\u063a \u062a\u0627\u064a\u0648\u0627\u0646 \u0633\u0641\u064a\u0631: \u0647\u0627\u062a\u0641: (+886) 4-2302-9080 to 1 \u0641\u0627\u0643\u0633: (+886) 4-2229-5900 \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a: \u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a: www.meco.org.tw \u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13091,16975,16952,15436],"tags":[15555],"class_list":["post-156892","post","type-post","status-publish","format-standard","hentry","category-13091","category-16975","category-16952","category-15436","tag-15555"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/156892"}],"collection":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/comments?post=156892"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/156892\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/media?parent=156892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/categories?post=156892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/tags?post=156892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}