{"id":156856,"date":"2019-09-01T17:08:19","date_gmt":"2019-09-01T17:08:19","guid":{"rendered":"https:\/\/travelqa.com\/%d8%a7%d9%84%d8%b1%d8%b3%d9%88%d9%84-%d8%a7%d9%84%d8%b1%d8%b3%d9%88%d9%84%d9%8a-%d9%84%d9%84%d9%83%d8%b1%d8%b3%d9%8a-%d8%a7%d9%84%d8%b1%d8%b3%d9%88%d9%84%d9%8a-%d9%81%d9%8a-%d8%aa%d8%a7%d9%8a%d8%a8\/"},"modified":"2019-09-01T17:08:19","modified_gmt":"2019-09-01T17:08:19","slug":"%d8%a7%d9%84%d8%b1%d8%b3%d9%88%d9%84-%d8%a7%d9%84%d8%b1%d8%b3%d9%88%d9%84%d9%8a-%d9%84%d9%84%d9%83%d8%b1%d8%b3%d9%8a-%d8%a7%d9%84%d8%b1%d8%b3%d9%88%d9%84%d9%8a-%d9%81%d9%8a-%d8%aa%d8%a7%d9%8a%d8%a8","status":"publish","type":"post","link":"https:\/\/travelqa.com\/ar\/%d8%a7%d9%84%d8%b1%d8%b3%d9%88%d9%84-%d8%a7%d9%84%d8%b1%d8%b3%d9%88%d9%84%d9%8a-%d9%84%d9%84%d9%83%d8%b1%d8%b3%d9%8a-%d8%a7%d9%84%d8%b1%d8%b3%d9%88%d9%84%d9%8a-%d9%81%d9%8a-%d8%aa%d8%a7%d9%8a%d8%a8\/","title":{"rendered":"\u0627\u0644\u0631\u0633\u0648\u0644 \u0627\u0644\u0631\u0633\u0648\u0644\u064a \u0644\u0644\u0643\u0631\u0633\u064a \u0627\u0644\u0631\u0633\u0648\u0644\u064a \u0641\u064a \u062a\u0627\u064a\u0628\u064a\u0647 \u060c \u062a\u0627\u064a\u0648\u0627\u0646"},"content":{"rendered":"<div id=\"trave-2998069133\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>\u0627\u0644\u0643\u0631\u0633\u064a \u0627\u0644\u0631\u0633\u0648\u0644\u064a \u0627\u0644\u0631\u0633\u0648\u0644\u064a \u062a\u0641\u0627\u0635\u064a\u0644 \u0641\u064a \u062a\u0627\u064a\u0628\u064a\u0647 \u060c \u062a\u0627\u064a\u0648\u0627\u0646<\/h3>\n<p><strong><br \/>\n\u0639\u0646\u0648\u0627\u0646:<\/strong><br \/>\n87 Aikuo East Road<br \/>\n\u062a\u0627\u064a\u0628\u064a\u064710642<br \/>\n\u062a\u0627\u064a\u0648\u0627\u0646<br \/>\n<strong><br \/>\n\u0633\u0641\u064a\u0631:<\/strong> \u0627\u0644\u0645\u0648\u0646\u0633\u0646\u064a\u0648\u0631 \u0633\u0644\u0627\u062f\u0627\u0646 \u0643\u0648\u0632\u064a\u062a\u0634 \u060c \u0627\u0644\u0642\u0627\u0626\u0645 \u0628\u0627\u0644\u0623\u0639\u0645\u0627\u0644 \u0628\u0627\u0644\u0646\u064a\u0627\u0628\u0629<br \/>\n<strong>\u0647\u0627\u062a\u0641:<\/strong> (+886) 2 2700-6847<br \/>\n<strong>\u0641\u0627\u0643\u0633:<\/strong> (+886) 2 2755-1926<br \/>\n<strong>\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> nuntius.taipei@gmail.com<br \/>\n<strong>\u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> <\/p>\n<p><strong>\u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/strong> <\/p>\n<div id=\"trave-1207488953\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0627\u0644\u0643\u0631\u0633\u064a \u0627\u0644\u0631\u0633\u0648\u0644\u064a \u0627\u0644\u0631\u0633\u0648\u0644\u064a \u062a\u0641\u0627\u0635\u064a\u0644 \u0641\u064a \u062a\u0627\u064a\u0628\u064a\u0647 \u060c \u062a\u0627\u064a\u0648\u0627\u0646 \u0639\u0646\u0648\u0627\u0646: 87 Aikuo East Road \u062a\u0627\u064a\u0628\u064a\u064710642 \u062a\u0627\u064a\u0648\u0627\u0646 \u0633\u0641\u064a\u0631: \u0627\u0644\u0645\u0648\u0646\u0633\u0646\u064a\u0648\u0631 \u0633\u0644\u0627\u062f\u0627\u0646 \u0643\u0648\u0632\u064a\u062a\u0634 \u060c \u0627\u0644\u0642\u0627\u0626\u0645 \u0628\u0627\u0644\u0623\u0639\u0645\u0627\u0644 \u0628\u0627\u0644\u0646\u064a\u0627\u0628\u0629 \u0647\u0627\u062a\u0641: (+886) 2 2700-6847 \u0641\u0627\u0643\u0633: (+886) 2 2755-1926 \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a: nuntius.taipei@gmail.com \u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a: \u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13125,13126,16958,15436],"tags":[13127],"class_list":["post-156856","post","type-post","status-publish","format-standard","hentry","category-13125","category-13126","category-16958","category-15436","tag-13127"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/156856"}],"collection":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/comments?post=156856"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/156856\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/media?parent=156856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/categories?post=156856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/tags?post=156856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}