{"id":156261,"date":"2019-09-01T17:00:03","date_gmt":"2019-09-01T17:00:03","guid":{"rendered":"https:\/\/travelqa.com\/%d8%b3%d9%81%d8%a7%d8%b1%d8%a9-%d8%a8%d9%88%d8%aa%d8%b3%d9%88%d8%a7%d9%86%d8%a7-%d9%81%d9%8a-%d8%b3%d8%aa%d9%88%d9%83%d9%87%d9%88%d9%84%d9%85-%d8%8c-%d8%a7%d9%84%d8%b3%d9%88%d9%8a%d8%af\/"},"modified":"2019-09-01T17:00:03","modified_gmt":"2019-09-01T17:00:03","slug":"%d8%b3%d9%81%d8%a7%d8%b1%d8%a9-%d8%a8%d9%88%d8%aa%d8%b3%d9%88%d8%a7%d9%86%d8%a7-%d9%81%d9%8a-%d8%b3%d8%aa%d9%88%d9%83%d9%87%d9%88%d9%84%d9%85-%d8%8c-%d8%a7%d9%84%d8%b3%d9%88%d9%8a%d8%af","status":"publish","type":"post","link":"https:\/\/travelqa.com\/ar\/%d8%b3%d9%81%d8%a7%d8%b1%d8%a9-%d8%a8%d9%88%d8%aa%d8%b3%d9%88%d8%a7%d9%86%d8%a7-%d9%81%d9%8a-%d8%b3%d8%aa%d9%88%d9%83%d9%87%d9%88%d9%84%d9%85-%d8%8c-%d8%a7%d9%84%d8%b3%d9%88%d9%8a%d8%af\/","title":{"rendered":"\u0633\u0641\u0627\u0631\u0629 \u0628\u0648\u062a\u0633\u0648\u0627\u0646\u0627 \u0641\u064a \u0633\u062a\u0648\u0643\u0647\u0648\u0644\u0645 \u060c \u0627\u0644\u0633\u0648\u064a\u062f"},"content":{"rendered":"<div id=\"trave-2028337298\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>\u062a\u0641\u0627\u0635\u064a\u0644 \u0633\u0641\u0627\u0631\u0629 \u0628\u0648\u062a\u0633\u0648\u0627\u0646\u0627 \u0641\u064a \u0633\u062a\u0648\u0643\u0647\u0648\u0644\u0645 \u060c \u0627\u0644\u0633\u0648\u064a\u062f<\/h3>\n<p><strong><br \/>\n\u0639\u0646\u0648\u0627\u0646:<\/strong><br \/>\nTyrgatan 11<br \/>\nBox 26024<br \/>\n100 41 Stockholm<br \/>\nSweden<br \/>\n<strong><br \/>\n\u0633\u0641\u064a\u0631:<\/strong> \u0627\u0644\u0633\u064a\u062f \u0644\u0627\u0645\u064a\u0643 \u0646\u062b\u064a\u0643\u064a\u0644\u0627 \u060c \u0627\u0644\u0633\u0641\u064a\u0631<br \/>\n<strong>\u0647\u0627\u062a\u0641:<\/strong> (+46) 8 545 258 80<br \/>\n<strong>\u0641\u0627\u0643\u0633:<\/strong> (+46) 8 723 00 87<br \/>\n<strong>\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> botstock@gov.bw<br \/>\n<strong>\u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> <\/p>\n<p><strong>\u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/strong> 09.00 &#8211; 13.00 \u0648 14.00 &#8211; 17.00<\/p>\n<div id=\"trave-4124526425\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u062a\u0641\u0627\u0635\u064a\u0644 \u0633\u0641\u0627\u0631\u0629 \u0628\u0648\u062a\u0633\u0648\u0627\u0646\u0627 \u0641\u064a \u0633\u062a\u0648\u0643\u0647\u0648\u0644\u0645 \u060c \u0627\u0644\u0633\u0648\u064a\u062f \u0639\u0646\u0648\u0627\u0646: Tyrgatan 11 Box 26024 100 41 Stockholm Sweden \u0633\u0641\u064a\u0631: \u0627\u0644\u0633\u064a\u062f \u0644\u0627\u0645\u064a\u0643 \u0646\u062b\u064a\u0643\u064a\u0644\u0627 \u060c \u0627\u0644\u0633\u0641\u064a\u0631 \u0647\u0627\u062a\u0641: (+46) 8 545 258 80 \u0641\u0627\u0643\u0633: (+46) 8 723 00 87 \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a: botstock@gov.bw \u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a: \u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644: 09.00 &#8211; 13.00 \u0648 14.00 &#8211; 17.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16933,13105,15589,15788],"tags":[12957],"class_list":["post-156261","post","type-post","status-publish","format-standard","hentry","category-16933","category-13105","category-15589","category-15788","tag-12957"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/156261"}],"collection":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/comments?post=156261"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/156261\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/media?parent=156261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/categories?post=156261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/tags?post=156261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}