{"id":156200,"date":"2019-09-01T16:59:26","date_gmt":"2019-09-01T16:59:26","guid":{"rendered":"https:\/\/travelqa.com\/%d8%a7%d9%84%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%a7%d9%84%d8%b9%d8%a7%d9%85%d8%a9-%d9%84%d9%84%d9%81%d9%84%d8%a8%d9%8a%d9%86-%d9%81%d9%8a-%d8%b3%d8%aa%d9%88%d9%83%d9%87%d9%88%d9%84%d9%85-%d8%8c\/"},"modified":"2019-09-01T16:59:26","modified_gmt":"2019-09-01T16:59:26","slug":"%d8%a7%d9%84%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%a7%d9%84%d8%b9%d8%a7%d9%85%d8%a9-%d9%84%d9%84%d9%81%d9%84%d8%a8%d9%8a%d9%86-%d9%81%d9%8a-%d8%b3%d8%aa%d9%88%d9%83%d9%87%d9%88%d9%84%d9%85-%d8%8c","status":"publish","type":"post","link":"https:\/\/travelqa.com\/ar\/%d8%a7%d9%84%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%a7%d9%84%d8%b9%d8%a7%d9%85%d8%a9-%d9%84%d9%84%d9%81%d9%84%d8%a8%d9%8a%d9%86-%d9%81%d9%8a-%d8%b3%d8%aa%d9%88%d9%83%d9%87%d9%88%d9%84%d9%85-%d8%8c\/","title":{"rendered":"\u0627\u0644\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u0639\u0627\u0645\u0629 \u0644\u0644\u0641\u0644\u0628\u064a\u0646 \u0641\u064a \u0633\u062a\u0648\u0643\u0647\u0648\u0644\u0645 \u060c \u0627\u0644\u0633\u0648\u064a\u062f"},"content":{"rendered":"<div id=\"trave-3456368639\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>\u0627\u0644\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u0641\u0644\u0628\u064a\u0646\u064a\u0629 \u062a\u0641\u0627\u0635\u064a\u0644 \u0639\u0627\u0645\u0629 \u0641\u064a \u0633\u062a\u0648\u0643\u0647\u0648\u0644\u0645 \u060c \u0627\u0644\u0633\u0648\u064a\u062f<\/h3>\n<p><strong><br \/>\n\u0639\u0646\u0648\u0627\u0646:<\/strong><br \/>\n114 39 \u0633\u062a\u0648\u0643\u0647\u0648\u0644\u0645<br \/>\n\u0627\u0644\u0633\u0648\u064a\u062f<br \/>\n<strong><br \/>\n\u0633\u0641\u064a\u0631:<\/strong> \u0625\u0631\u064a\u0643 \u0628\u0644\u0641\u0631\u0627\u062c \u060c \u0627\u0644\u0642\u0646\u0635\u0644 \u0627\u0644\u0641\u062e\u0631\u064a \u0627\u0644\u0639\u0627\u0645<br \/>\n<strong>\u0647\u0627\u062a\u0641:<\/strong> (+46) 725 329 933<br \/>\n<strong>\u0641\u0627\u0643\u0633:<\/strong><br \/>\n<strong>\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> philcon.se@gmail.com<br \/>\n<strong>\u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> <\/p>\n<p><strong>\u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/strong> \u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0647\u0627\u062a\u0641: \u0627\u0644\u0627\u062b\u0646\u064a\u0646 \u0648\u0627\u0644\u0623\u0631\u0628\u0639\u0627\u0621: 13.00-15.00<\/p>\n<div id=\"trave-488482791\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0627\u0644\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u0641\u0644\u0628\u064a\u0646\u064a\u0629 \u062a\u0641\u0627\u0635\u064a\u0644 \u0639\u0627\u0645\u0629 \u0641\u064a \u0633\u062a\u0648\u0643\u0647\u0648\u0644\u0645 \u060c \u0627\u0644\u0633\u0648\u064a\u062f \u0639\u0646\u0648\u0627\u0646: 114 39 \u0633\u062a\u0648\u0643\u0647\u0648\u0644\u0645 \u0627\u0644\u0633\u0648\u064a\u062f \u0633\u0641\u064a\u0631: \u0625\u0631\u064a\u0643 \u0628\u0644\u0641\u0631\u0627\u062c \u060c \u0627\u0644\u0642\u0646\u0635\u0644 \u0627\u0644\u0641\u062e\u0631\u064a \u0627\u0644\u0639\u0627\u0645 \u0647\u0627\u062a\u0641: (+46) 725 329 933 \u0641\u0627\u0643\u0633: \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a: philcon.se@gmail.com \u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a: \u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644: \u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0647\u0627\u062a\u0641: \u0627\u0644\u0627\u062b\u0646\u064a\u0646 \u0648\u0627\u0644\u0623\u0631\u0628\u0639\u0627\u0621: 13.00-15.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13105,13091,16932,15336],"tags":[12962],"class_list":["post-156200","post","type-post","status-publish","format-standard","hentry","category-13105","category-13091","category-16932","category-15336","tag-12962"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/156200"}],"collection":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/comments?post=156200"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/156200\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/media?parent=156200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/categories?post=156200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/tags?post=156200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}