{"id":155551,"date":"2019-09-01T16:52:06","date_gmt":"2019-09-01T16:52:06","guid":{"rendered":"https:\/\/travelqa.com\/%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%a7%d9%84%d9%85%d9%85%d9%84%d9%83%d8%a9-%d8%a7%d9%84%d9%85%d8%aa%d8%ad%d8%af%d8%a9-%d9%81%d9%8a-%d9%85%d9%84%d9%82%d8%a9-%d8%8c-%d8%a7%d8%b3%d8%a8%d8%a7%d9%86\/"},"modified":"2019-09-01T16:52:06","modified_gmt":"2019-09-01T16:52:06","slug":"%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%a7%d9%84%d9%85%d9%85%d9%84%d9%83%d8%a9-%d8%a7%d9%84%d9%85%d8%aa%d8%ad%d8%af%d8%a9-%d9%81%d9%8a-%d9%85%d9%84%d9%82%d8%a9-%d8%8c-%d8%a7%d8%b3%d8%a8%d8%a7%d9%86","status":"publish","type":"post","link":"https:\/\/travelqa.com\/ar\/%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%a7%d9%84%d9%85%d9%85%d9%84%d9%83%d8%a9-%d8%a7%d9%84%d9%85%d8%aa%d8%ad%d8%af%d8%a9-%d9%81%d9%8a-%d9%85%d9%84%d9%82%d8%a9-%d8%8c-%d8%a7%d8%b3%d8%a8%d8%a7%d9%86\/","title":{"rendered":"\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u0645\u0645\u0644\u0643\u0629 \u0627\u0644\u0645\u062a\u062d\u062f\u0629 \u0641\u064a \u0645\u0644\u0642\u0629 \u060c \u0627\u0633\u0628\u0627\u0646\u064a\u0627"},"content":{"rendered":"<div id=\"trave-3808161918\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u0628\u0631\u064a\u0637\u0627\u0646\u064a\u0629 \u0641\u064a \u0645\u0644\u0642\u0629 \u060c \u0625\u0633\u0628\u0627\u0646\u064a\u0627<\/h3>\n<p><strong><br \/>\n\u0639\u0646\u0648\u0627\u0646:<\/strong><br \/>\nEdificio EUROCOM<br \/>\nC \/ Mauricio Moro Pareto\u060c 2\u060c 2<br \/>\n29006 M\u00c3\u00a1laga<br \/>\nSpain<br \/>\n<strong><br \/>\n\u0633\u0641\u064a\u0631:<\/strong> \u0627\u0644\u0633\u064a\u062f\u0629 \u0634\u0627\u0631\u0645\u064a\u0646 \u0623\u0631\u0628\u0648\u064a\u0646 \u060c \u0627\u0644\u0642\u0646\u0635\u0644<br \/>\n<strong>\u0647\u0627\u062a\u0641:<\/strong> (+34) 952 35 23 00<br \/>\n<strong>\u0641\u0627\u0643\u0633:<\/strong> (+34) 95 235 9211<br \/>\n<strong>\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> spain.consulate@fco.gov.uk<br \/>\n<strong>\u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> <\/p>\n<p><strong>\u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/strong> <\/p>\n<div id=\"trave-1627365963\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u0628\u0631\u064a\u0637\u0627\u0646\u064a\u0629 \u0641\u064a \u0645\u0644\u0642\u0629 \u060c \u0625\u0633\u0628\u0627\u0646\u064a\u0627 \u0639\u0646\u0648\u0627\u0646: Edificio EUROCOM C \/ Mauricio Moro Pareto\u060c 2\u060c 2 29006 M\u00c3\u00a1laga Spain \u0633\u0641\u064a\u0631: \u0627\u0644\u0633\u064a\u062f\u0629 \u0634\u0627\u0631\u0645\u064a\u0646 \u0623\u0631\u0628\u0648\u064a\u0646 \u060c \u0627\u0644\u0642\u0646\u0635\u0644 \u0647\u0627\u062a\u0641: (+34) 952 35 23 00 \u0641\u0627\u0643\u0633: (+34) 95 235 9211 \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a: spain.consulate@fco.gov.uk \u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a: \u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13200,15326,16909,13099],"tags":[12951],"class_list":["post-155551","post","type-post","status-publish","format-standard","hentry","category-13200","category-15326","category-16909","category-13099","tag-12951"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/155551"}],"collection":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/comments?post=155551"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/155551\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/media?parent=155551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/categories?post=155551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/tags?post=155551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}