{"id":155436,"date":"2019-09-01T16:51:03","date_gmt":"2019-09-01T16:51:03","guid":{"rendered":"https:\/\/travelqa.com\/%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%ac%d9%85%d9%87%d9%88%d8%b1%d9%8a%d8%a9-%d8%a7%d9%84%d8%af%d9%88%d9%85%d9%8a%d9%86%d9%8a%d9%83%d8%a7%d9%86-%d9%81%d9%8a-%d9%81%d8%a7%d9%84%d9%86%d8%b3%d9%8a\/"},"modified":"2019-09-01T16:51:03","modified_gmt":"2019-09-01T16:51:03","slug":"%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%ac%d9%85%d9%87%d9%88%d8%b1%d9%8a%d8%a9-%d8%a7%d9%84%d8%af%d9%88%d9%85%d9%8a%d9%86%d9%8a%d9%83%d8%a7%d9%86-%d9%81%d9%8a-%d9%81%d8%a7%d9%84%d9%86%d8%b3%d9%8a","status":"publish","type":"post","link":"https:\/\/travelqa.com\/ar\/%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%ac%d9%85%d9%87%d9%88%d8%b1%d9%8a%d8%a9-%d8%a7%d9%84%d8%af%d9%88%d9%85%d9%8a%d9%86%d9%8a%d9%83%d8%a7%d9%86-%d9%81%d9%8a-%d9%81%d8%a7%d9%84%d9%86%d8%b3%d9%8a\/","title":{"rendered":"\u0642\u0646\u0635\u0644\u064a\u0629 \u062c\u0645\u0647\u0648\u0631\u064a\u0629 \u0627\u0644\u062f\u0648\u0645\u064a\u0646\u064a\u0643\u0627\u0646 \u0641\u064a \u0641\u0627\u0644\u0646\u0633\u064a\u0627 \u060c \u0627\u0633\u0628\u0627\u0646\u064a\u0627"},"content":{"rendered":"<div id=\"trave-1532883004\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u062f\u0648\u0645\u064a\u0646\u064a\u0643\u064a\u0629 \u0641\u064a \u0641\u0627\u0644\u0646\u0633\u064a\u0627 \u060c \u0625\u0633\u0628\u0627\u0646\u064a\u0627<\/h3>\n<p><strong><br \/>\n\u0639\u0646\u0648\u0627\u0646:<\/strong><br \/>\nC \/ San Vicente Better 100 2\u00c2\u00ba-2\u00c2\u00ba<br \/>\n46007 Valencia<br \/>\nSpain<br \/>\n<strong><br \/>\n\u0633\u0641\u064a\u0631:<\/strong> \u062e\u0648\u0631\u062e\u064a \u0646\u064a\u0643\u0648\u0644 \u0643\u0648\u0631\u062f\u064a\u0631\u0648 \u0628\u0627\u0634 \u060c \u0627\u0644\u0642\u0646\u0635\u0644<br \/>\n<strong>\u0647\u0627\u062a\u0641:<\/strong> (+34) (96) 352-1780<br \/>\n<strong>\u0641\u0627\u0643\u0633:<\/strong><br \/>\n<strong>\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> valenciaconsuladord@gmail.com<br \/>\nconsulrdvalencia@gmail.com<br \/>\n<strong>\u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> www.consuladordvalencia.com<\/p>\n<p><strong>\u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/strong> 09.00-16.00<\/p>\n<div id=\"trave-1704299453\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u062f\u0648\u0645\u064a\u0646\u064a\u0643\u064a\u0629 \u0641\u064a \u0641\u0627\u0644\u0646\u0633\u064a\u0627 \u060c \u0625\u0633\u0628\u0627\u0646\u064a\u0627 \u0639\u0646\u0648\u0627\u0646: C \/ San Vicente Better 100 2\u00c2\u00ba-2\u00c2\u00ba 46007 Valencia Spain \u0633\u0641\u064a\u0631: \u062e\u0648\u0631\u062e\u064a \u0646\u064a\u0643\u0648\u0644 \u0643\u0648\u0631\u062f\u064a\u0631\u0648 \u0628\u0627\u0634 \u060c \u0627\u0644\u0642\u0646\u0635\u0644 \u0647\u0627\u062a\u0641: (+34) (96) 352-1780 \u0641\u0627\u0643\u0633: \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a: valenciaconsuladord@gmail.com consulrdvalencia@gmail.com \u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a: www.consuladordvalencia.com \u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644: 09.00-16.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13200,15324,16909,15323],"tags":[12951],"class_list":["post-155436","post","type-post","status-publish","format-standard","hentry","category-13200","category-15324","category-16909","category-15323","tag-12951"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/155436"}],"collection":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/comments?post=155436"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/155436\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/media?parent=155436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/categories?post=155436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/tags?post=155436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}