{"id":155410,"date":"2019-09-01T16:50:37","date_gmt":"2019-09-01T16:50:37","guid":{"rendered":"https:\/\/travelqa.com\/%d8%a7%d9%84%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%a7%d9%84%d8%b9%d8%a7%d9%85%d8%a9-%d9%84%d8%b3%d9%84%d9%88%d9%81%d8%a7%d9%83%d9%8a%d8%a7-%d9%81%d9%8a-%d8%a8%d8%b1%d8%b4%d9%84%d9%88%d9%86%d8%a9\/"},"modified":"2019-09-01T16:50:37","modified_gmt":"2019-09-01T16:50:37","slug":"%d8%a7%d9%84%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%a7%d9%84%d8%b9%d8%a7%d9%85%d8%a9-%d9%84%d8%b3%d9%84%d9%88%d9%81%d8%a7%d9%83%d9%8a%d8%a7-%d9%81%d9%8a-%d8%a8%d8%b1%d8%b4%d9%84%d9%88%d9%86%d8%a9","status":"publish","type":"post","link":"https:\/\/travelqa.com\/ar\/%d8%a7%d9%84%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%a7%d9%84%d8%b9%d8%a7%d9%85%d8%a9-%d9%84%d8%b3%d9%84%d9%88%d9%81%d8%a7%d9%83%d9%8a%d8%a7-%d9%81%d9%8a-%d8%a8%d8%b1%d8%b4%d9%84%d9%88%d9%86%d8%a9\/","title":{"rendered":"\u0627\u0644\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u0639\u0627\u0645\u0629 \u0644\u0633\u0644\u0648\u0641\u0627\u0643\u064a\u0627 \u0641\u064a \u0628\u0631\u0634\u0644\u0648\u0646\u0629 \u060c \u0627\u0633\u0628\u0627\u0646\u064a\u0627"},"content":{"rendered":"<div id=\"trave-2499640116\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>\u0627\u0644\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u0633\u0644\u0648\u0641\u0627\u0643\u064a\u0629 \u0627\u0644\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0639\u0627\u0645\u0629 \u0641\u064a \u0628\u0631\u0634\u0644\u0648\u0646\u0629 \u060c \u0627\u0633\u0628\u0627\u0646\u064a\u0627<\/h3>\n<p><strong><br \/>\n\u0639\u0646\u0648\u0627\u0646:<\/strong><br \/>\nRambla de Catalunya\u060c 135\u060c 1 tic 1a<br \/>\n08008 Barcelona<br \/>\nSpain<br \/>\n<strong><br \/>\n\u0633\u0641\u064a\u0631:<\/strong> \u0627\u0644\u0633\u064a\u062f \u062c\u0648\u0627\u0646 \u0625\u062c\u0646\u0627\u0633\u064a\u0648 \u062a\u0648\u0631\u064a\u062f\u064a\u0645\u064a\u0631 \u060c \u0627\u0644\u0642\u0646\u0635\u0644 \u0627\u0644\u0641\u062e\u0631\u064a \u0627\u0644\u0639\u0627\u0645<br \/>\n<strong>\u0647\u0627\u062a\u0641:<\/strong> (+34) 93 317 94 65<br \/>\n(+34) 93 412 08 92<br \/>\n<strong>\u0641\u0627\u0643\u0633:<\/strong> (+34) 93 317 17 93<br \/>\n<strong>\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> consulateslovaquiabcn@torredemer.com<br \/>\n<strong>\u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> <\/p>\n<p><strong>\u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/strong> <\/p>\n<div id=\"trave-1829513931\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0627\u0644\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u0633\u0644\u0648\u0641\u0627\u0643\u064a\u0629 \u0627\u0644\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0639\u0627\u0645\u0629 \u0641\u064a \u0628\u0631\u0634\u0644\u0648\u0646\u0629 \u060c \u0627\u0633\u0628\u0627\u0646\u064a\u0627 \u0639\u0646\u0648\u0627\u0646: Rambla de Catalunya\u060c 135\u060c 1 tic 1a 08008 Barcelona Spain \u0633\u0641\u064a\u0631: \u0627\u0644\u0633\u064a\u062f \u062c\u0648\u0627\u0646 \u0625\u062c\u0646\u0627\u0633\u064a\u0648 \u062a\u0648\u0631\u064a\u062f\u064a\u0645\u064a\u0631 \u060c \u0627\u0644\u0642\u0646\u0635\u0644 \u0627\u0644\u0641\u062e\u0631\u064a \u0627\u0644\u0639\u0627\u0645 \u0647\u0627\u062a\u0641: (+34) 93 317 94 65 (+34) 93 412 08 92 \u0641\u0627\u0643\u0633: (+34) 93 317 17 93 \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a: consulateslovaquiabcn@torredemer.com \u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a: \u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13200,15434,16910,13095],"tags":[12962],"class_list":["post-155410","post","type-post","status-publish","format-standard","hentry","category-13200","category-15434","category-16910","category-13095","tag-12962"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/155410"}],"collection":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/comments?post=155410"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/155410\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/media?parent=155410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/categories?post=155410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/tags?post=155410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}