{"id":154498,"date":"2019-09-01T16:40:13","date_gmt":"2019-09-01T16:40:13","guid":{"rendered":"https:\/\/travelqa.com\/%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d9%82%d8%a8%d8%b1%d8%b5-%d9%81%d9%8a-%d9%81%d9%8a%d9%83%d8%aa%d9%88%d8%b1%d9%8a%d8%a7-%d8%8c-%d8%b3%d9%8a%d8%b4%d9%8a%d9%84\/"},"modified":"2019-09-01T16:40:13","modified_gmt":"2019-09-01T16:40:13","slug":"%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d9%82%d8%a8%d8%b1%d8%b5-%d9%81%d9%8a-%d9%81%d9%8a%d9%83%d8%aa%d9%88%d8%b1%d9%8a%d8%a7-%d8%8c-%d8%b3%d9%8a%d8%b4%d9%8a%d9%84","status":"publish","type":"post","link":"https:\/\/travelqa.com\/ar\/%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d9%82%d8%a8%d8%b1%d8%b5-%d9%81%d9%8a-%d9%81%d9%8a%d9%83%d8%aa%d9%88%d8%b1%d9%8a%d8%a7-%d8%8c-%d8%b3%d9%8a%d8%b4%d9%8a%d9%84\/","title":{"rendered":"\u0642\u0646\u0635\u0644\u064a\u0629 \u0642\u0628\u0631\u0635 \u0641\u064a \u0641\u064a\u0643\u062a\u0648\u0631\u064a\u0627 \u060c \u0633\u064a\u0634\u064a\u0644"},"content":{"rendered":"<div id=\"trave-1115993939\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u0642\u0628\u0631\u0635\u064a\u0629 \u0641\u064a \u0641\u064a\u0643\u062a\u0648\u0631\u064a\u0627 \u060c \u0633\u064a\u0634\u064a\u0644<\/h3>\n<p><strong><br \/>\n\u0639\u0646\u0648\u0627\u0646:<\/strong><br \/>\n\u0645\u0637\u0627\u0631 \u0633\u064a\u0634\u064a\u0644 \u0627\u0644\u062f\u0648\u0644\u064a<br \/>\nP O Box 450<br \/>\nVictoria\u060c Mah\u00c3 \u00a9<br \/>\nSeychelles<br \/>\n<strong><br \/>\n\u0633\u0641\u064a\u0631:<\/strong> \u0627\u0644\u0633\u064a\u062f \u0646\u064a\u0641\u064a\u0644 \u0645\u0648\u0631\u064a\u0644 \u060c \u0646\u0627\u0626\u0628 \u0627\u0644\u0642\u0646\u0635\u0644 \u0627\u0644\u0641\u062e\u0631\u064a<br \/>\n<strong>\u0647\u0627\u062a\u0641:<\/strong> (+248) 438 1750<br \/>\n(+248) 438 1752<br \/>\n<strong>\u0641\u0627\u0643\u0633:<\/strong> (+248) 437 3456<br \/>\n<strong>\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> panosco@cytanet.com.cy<br \/>\nneville@seychelles.net<br \/>\n<strong>\u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> <\/p>\n<p><strong>\u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/strong> 09.00-15.00<\/p>\n<div id=\"trave-3681878825\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u0642\u0628\u0631\u0635\u064a\u0629 \u0641\u064a \u0641\u064a\u0643\u062a\u0648\u0631\u064a\u0627 \u060c \u0633\u064a\u0634\u064a\u0644 \u0639\u0646\u0648\u0627\u0646: \u0645\u0637\u0627\u0631 \u0633\u064a\u0634\u064a\u0644 \u0627\u0644\u062f\u0648\u0644\u064a P O Box 450 Victoria\u060c Mah\u00c3 \u00a9 Seychelles \u0633\u0641\u064a\u0631: \u0627\u0644\u0633\u064a\u062f \u0646\u064a\u0641\u064a\u0644 \u0645\u0648\u0631\u064a\u0644 \u060c \u0646\u0627\u0626\u0628 \u0627\u0644\u0642\u0646\u0635\u0644 \u0627\u0644\u0641\u062e\u0631\u064a \u0647\u0627\u062a\u0641: (+248) 438 1750 (+248) 438 1752 \u0641\u0627\u0643\u0633: (+248) 437 3456 \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a: panosco@cytanet.com.cy neville@seychelles.net \u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a: \u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644: 09.00-15.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13322,16852,15501,13321],"tags":[12951],"class_list":["post-154498","post","type-post","status-publish","format-standard","hentry","category-13322","category-16852","category-15501","category-13321","tag-12951"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/154498"}],"collection":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/comments?post=154498"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/154498\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/media?parent=154498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/categories?post=154498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/tags?post=154498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}