{"id":154482,"date":"2019-09-01T16:39:43","date_gmt":"2019-09-01T16:39:43","guid":{"rendered":"https:\/\/travelqa.com\/%d8%b3%d9%81%d8%a7%d8%b1%d8%a9-%d8%a3%d8%b0%d8%b1%d8%a8%d9%8a%d8%ac%d8%a7%d9%86-%d9%81%d9%8a-%d8%a8%d9%84%d8%ba%d8%b1%d8%a7%d8%af-%d8%8c-%d8%b5%d8%b1%d8%a8%d9%8a%d8%a7\/"},"modified":"2019-09-01T16:39:43","modified_gmt":"2019-09-01T16:39:43","slug":"%d8%b3%d9%81%d8%a7%d8%b1%d8%a9-%d8%a3%d8%b0%d8%b1%d8%a8%d9%8a%d8%ac%d8%a7%d9%86-%d9%81%d9%8a-%d8%a8%d9%84%d8%ba%d8%b1%d8%a7%d8%af-%d8%8c-%d8%b5%d8%b1%d8%a8%d9%8a%d8%a7","status":"publish","type":"post","link":"https:\/\/travelqa.com\/ar\/%d8%b3%d9%81%d8%a7%d8%b1%d8%a9-%d8%a3%d8%b0%d8%b1%d8%a8%d9%8a%d8%ac%d8%a7%d9%86-%d9%81%d9%8a-%d8%a8%d9%84%d8%ba%d8%b1%d8%a7%d8%af-%d8%8c-%d8%b5%d8%b1%d8%a8%d9%8a%d8%a7\/","title":{"rendered":"\u0633\u0641\u0627\u0631\u0629 \u0623\u0630\u0631\u0628\u064a\u062c\u0627\u0646 \u0641\u064a \u0628\u0644\u063a\u0631\u0627\u062f \u060c \u0635\u0631\u0628\u064a\u0627"},"content":{"rendered":"<div id=\"trave-2793508858\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0633\u0641\u0627\u0631\u0629 \u0627\u0644\u0623\u0630\u0631\u0628\u064a\u062c\u0627\u0646\u064a\u0629 \u0641\u064a \u0628\u0644\u063a\u0631\u0627\u062f \u060c \u0635\u0631\u0628\u064a\u0627<\/h3>\n<p><strong><br \/>\n\u0639\u0646\u0648\u0627\u0646:<\/strong><br \/>\n\u0627\u0644\u0645\u0627\u0644 \u0641\u064a\u0644\u064a\u0645\u064a\u0631\u0648\u0641\u064a\u062a\u0634\u0627 25<br \/>\n\u0628\u0644\u063a\u0631\u0627\u062f<br \/>\n\u0635\u0631\u0628\u064a\u0627<br \/>\n<strong><br \/>\n\u0633\u0641\u064a\u0631:<\/strong> \u0627\u0644\u0633\u064a\u062f \u0625\u0644\u062f\u0627\u0631 \u062d\u0633\u0646\u0648\u0641 \u060c \u0627\u0644\u0633\u0641\u064a\u0631<br \/>\n<strong>\u0647\u0627\u062a\u0641:<\/strong> (+381) 11 3515 101<br \/>\n(+381) 11 3515 102<br \/>\n<strong>\u0641\u0627\u0643\u0633:<\/strong> (+381) 11 3515 103<br \/>\n<strong>\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> belgrade@mission.mfa.gov.az<br \/>\n<strong>\u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> belgrade.mfa.gov.az<\/p>\n<p><strong>\u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/strong> 09.00-18.00<\/p>\n<div id=\"trave-2918017686\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0633\u0641\u0627\u0631\u0629 \u0627\u0644\u0623\u0630\u0631\u0628\u064a\u062c\u0627\u0646\u064a\u0629 \u0641\u064a \u0628\u0644\u063a\u0631\u0627\u062f \u060c \u0635\u0631\u0628\u064a\u0627 \u0639\u0646\u0648\u0627\u0646: \u0627\u0644\u0645\u0627\u0644 \u0641\u064a\u0644\u064a\u0645\u064a\u0631\u0648\u0641\u064a\u062a\u0634\u0627 25 \u0628\u0644\u063a\u0631\u0627\u062f \u0635\u0631\u0628\u064a\u0627 \u0633\u0641\u064a\u0631: \u0627\u0644\u0633\u064a\u062f \u0625\u0644\u062f\u0627\u0631 \u062d\u0633\u0646\u0648\u0641 \u060c \u0627\u0644\u0633\u0641\u064a\u0631 \u0647\u0627\u062a\u0641: (+381) 11 3515 101 (+381) 11 3515 102 \u0641\u0627\u0643\u0633: (+381) 11 3515 103 \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a: belgrade@mission.mfa.gov.az \u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a: belgrade.mfa.gov.az \u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644: 09.00-18.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15283,15284,16845,13112],"tags":[12957],"class_list":["post-154482","post","type-post","status-publish","format-standard","hentry","category-15283","category-15284","category-16845","category-13112","tag-12957"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/154482"}],"collection":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/comments?post=154482"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/154482\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/media?parent=154482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/categories?post=154482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/tags?post=154482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}