{"id":152542,"date":"2019-09-01T16:16:38","date_gmt":"2019-09-01T16:16:38","guid":{"rendered":"https:\/\/travelqa.com\/%d8%b3%d9%81%d8%a7%d8%b1%d8%a9-%d8%a7%d9%84%d8%ac%d8%b2%d8%a7%d8%a6%d8%b1-%d9%81%d9%8a-%d9%84%d9%8a%d9%85%d8%a7-%d8%8c-%d8%a8%d9%8a%d8%b1%d9%88\/"},"modified":"2019-09-01T16:16:38","modified_gmt":"2019-09-01T16:16:38","slug":"%d8%b3%d9%81%d8%a7%d8%b1%d8%a9-%d8%a7%d9%84%d8%ac%d8%b2%d8%a7%d8%a6%d8%b1-%d9%81%d9%8a-%d9%84%d9%8a%d9%85%d8%a7-%d8%8c-%d8%a8%d9%8a%d8%b1%d9%88","status":"publish","type":"post","link":"https:\/\/travelqa.com\/ar\/%d8%b3%d9%81%d8%a7%d8%b1%d8%a9-%d8%a7%d9%84%d8%ac%d8%b2%d8%a7%d8%a6%d8%b1-%d9%81%d9%8a-%d9%84%d9%8a%d9%85%d8%a7-%d8%8c-%d8%a8%d9%8a%d8%b1%d9%88\/","title":{"rendered":"\u0633\u0641\u0627\u0631\u0629 \u0627\u0644\u062c\u0632\u0627\u0626\u0631 \u0641\u064a \u0644\u064a\u0645\u0627 \u060c \u0628\u064a\u0631\u0648"},"content":{"rendered":"<div id=\"trave-860055995\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0633\u0641\u0627\u0631\u0629 \u0627\u0644\u062c\u0632\u0627\u0626\u0631\u064a\u0629 \u0641\u064a \u0644\u064a\u0645\u0627 \u060c \u0628\u064a\u0631\u0648<\/h3>\n<p><strong><br \/>\n\u0639\u0646\u0648\u0627\u0646:<\/strong><br \/>\nLucha de Liberaci\u00f3n Nacional<br \/>\nAv.El Rosario N\u00c2\u00ba 380<br \/>\nSan Isidro<br \/>\nLima 27<br \/>\nPeru<br \/>\n<strong><br \/>\n\u0633\u0641\u064a\u0631:<\/strong> \u0627\u0644\u0633\u064a\u062f \u0634\u0643\u064a\u0628 \u0631\u0634\u064a\u062f \u0643\u0627\u064a\u062f \u060c \u0627\u0644\u0633\u0641\u064a\u0631<br \/>\n<strong>\u0647\u0627\u062a\u0641:<\/strong> (+51) 1 421 7580<br \/>\n(+51) 1 421 7583<br \/>\n<strong>\u0641\u0627\u0643\u0633:<\/strong> (+51) 1 421 7580<br \/>\n<strong>\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong><br \/>\n<strong>\u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> <\/p>\n<p><strong>\u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/strong> 09.00-16.00<\/p>\n<div id=\"trave-472005000\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0633\u0641\u0627\u0631\u0629 \u0627\u0644\u062c\u0632\u0627\u0626\u0631\u064a\u0629 \u0641\u064a \u0644\u064a\u0645\u0627 \u060c \u0628\u064a\u0631\u0648 \u0639\u0646\u0648\u0627\u0646: Lucha de Liberaci\u00f3n Nacional Av.El Rosario N\u00c2\u00ba 380 San Isidro Lima 27 Peru \u0633\u0641\u064a\u0631: \u0627\u0644\u0633\u064a\u062f \u0634\u0643\u064a\u0628 \u0631\u0634\u064a\u062f \u0643\u0627\u064a\u062f \u060c \u0627\u0644\u0633\u0641\u064a\u0631 \u0647\u0627\u062a\u0641: (+51) 1 421 7580 (+51) 1 421 7583 \u0641\u0627\u0643\u0633: (+51) 1 421 7580 \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a: \u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a: \u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644: 09.00-16.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13215,13216,16735,13405],"tags":[12957],"class_list":["post-152542","post","type-post","status-publish","format-standard","hentry","category-13215","category-13216","category-16735","category-13405","tag-12957"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/152542"}],"collection":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/comments?post=152542"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/152542\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/media?parent=152542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/categories?post=152542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/tags?post=152542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}