{"id":150572,"date":"2019-09-01T15:45:57","date_gmt":"2019-09-01T15:45:57","guid":{"rendered":"https:\/\/travelqa.com\/%d8%a7%d9%84%d9%85%d9%81%d9%88%d8%b6%d9%8a%d8%a9-%d8%a7%d9%84%d8%b9%d9%84%d9%8a%d8%a7-%d9%84%d8%ac%d9%86%d9%88%d8%a8-%d8%a5%d9%81%d8%b1%d9%8a%d9%82%d9%8a%d8%a7-%d9%81%d9%8a-%d9%85%d8%a7%d8%a8%d9%88\/"},"modified":"2019-09-01T15:45:57","modified_gmt":"2019-09-01T15:45:57","slug":"%d8%a7%d9%84%d9%85%d9%81%d9%88%d8%b6%d9%8a%d8%a9-%d8%a7%d9%84%d8%b9%d9%84%d9%8a%d8%a7-%d9%84%d8%ac%d9%86%d9%88%d8%a8-%d8%a5%d9%81%d8%b1%d9%8a%d9%82%d9%8a%d8%a7-%d9%81%d9%8a-%d9%85%d8%a7%d8%a8%d9%88","status":"publish","type":"post","link":"https:\/\/travelqa.com\/ar\/%d8%a7%d9%84%d9%85%d9%81%d9%88%d8%b6%d9%8a%d8%a9-%d8%a7%d9%84%d8%b9%d9%84%d9%8a%d8%a7-%d9%84%d8%ac%d9%86%d9%88%d8%a8-%d8%a5%d9%81%d8%b1%d9%8a%d9%82%d9%8a%d8%a7-%d9%81%d9%8a-%d9%85%d8%a7%d8%a8%d9%88\/","title":{"rendered":"\u0627\u0644\u0645\u0641\u0648\u0636\u064a\u0629 \u0627\u0644\u0639\u0644\u064a\u0627 \u0644\u062c\u0646\u0648\u0628 \u0625\u0641\u0631\u064a\u0642\u064a\u0627 \u0641\u064a \u0645\u0627\u0628\u0648\u062a\u0648 \u060c \u0645\u0648\u0632\u0645\u0628\u064a\u0642"},"content":{"rendered":"<div id=\"trave-2226738115\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0645\u0641\u0648\u0636\u064a\u0629 \u0627\u0644\u0639\u0644\u064a\u0627 \u0644\u062c\u0646\u0648\u0628 \u0625\u0641\u0631\u064a\u0642\u064a\u0627 \u0641\u064a \u0645\u0627\u0628\u0648\u062a\u0648 \u060c \u0645\u0648\u0632\u0645\u0628\u064a\u0642<\/h3>\n<p><strong><br \/>\n\u0639\u0646\u0648\u0627\u0646:<\/strong><br \/>\nCaixa Postal 1120<br \/>\nMaputo<br \/>\nMozambique<br \/>\n<strong><br \/>\n\u0633\u0641\u064a\u0631:<\/strong><br \/>\n<strong>\u0647\u0627\u062a\u0641:<\/strong> (+258) 21 243 000<br \/>\n<strong>\u0641\u0627\u0643\u0633:<\/strong> (+258) 21 488 897<br \/>\n(+258) 21 49 2533<br \/>\n<strong>\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong><br \/>\n<strong>\u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> www.dirco.gov.za\/maputo\/<\/p>\n<p><strong>\u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/strong> 08.00-16.00<\/p>\n<div id=\"trave-1862903822\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0645\u0641\u0648\u0636\u064a\u0629 \u0627\u0644\u0639\u0644\u064a\u0627 \u0644\u062c\u0646\u0648\u0628 \u0625\u0641\u0631\u064a\u0642\u064a\u0627 \u0641\u064a \u0645\u0627\u0628\u0648\u062a\u0648 \u060c \u0645\u0648\u0632\u0645\u0628\u064a\u0642 \u0639\u0646\u0648\u0627\u0646: Caixa Postal 1120 Maputo Mozambique \u0633\u0641\u064a\u0631: \u0647\u0627\u062a\u0641: (+258) 21 243 000 \u0641\u0627\u0643\u0633: (+258) 21 488 897 (+258) 21 49 2533 \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a: \u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a: www.dirco.gov.za\/maputo\/ \u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644: 08.00-16.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16595,15507,13118,15319],"tags":[15508],"class_list":["post-150572","post","type-post","status-publish","format-standard","hentry","category-16595","category-15507","category-13118","category-15319","tag-15508"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/150572"}],"collection":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/comments?post=150572"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/150572\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/media?parent=150572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/categories?post=150572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/tags?post=150572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}