{"id":150001,"date":"2019-09-01T15:38:33","date_gmt":"2019-09-01T15:38:33","guid":{"rendered":"https:\/\/travelqa.com\/%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%a8%d9%88%d8%aa%d8%b3%d9%88%d8%a7%d9%86%d8%a7-%d9%81%d9%8a-%d9%85%d9%83%d8%b3%d9%8a%d9%83%d9%88-%d8%b3%d9%8a%d8%aa%d9%8a-%d8%8c-%d8%a7%d9%84%d9%85%d9%83%d8%b3\/"},"modified":"2019-09-01T15:38:33","modified_gmt":"2019-09-01T15:38:33","slug":"%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%a8%d9%88%d8%aa%d8%b3%d9%88%d8%a7%d9%86%d8%a7-%d9%81%d9%8a-%d9%85%d9%83%d8%b3%d9%8a%d9%83%d9%88-%d8%b3%d9%8a%d8%aa%d9%8a-%d8%8c-%d8%a7%d9%84%d9%85%d9%83%d8%b3","status":"publish","type":"post","link":"https:\/\/travelqa.com\/ar\/%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%a8%d9%88%d8%aa%d8%b3%d9%88%d8%a7%d9%86%d8%a7-%d9%81%d9%8a-%d9%85%d9%83%d8%b3%d9%8a%d9%83%d9%88-%d8%b3%d9%8a%d8%aa%d9%8a-%d8%8c-%d8%a7%d9%84%d9%85%d9%83%d8%b3\/","title":{"rendered":"\u0642\u0646\u0635\u0644\u064a\u0629 \u0628\u0648\u062a\u0633\u0648\u0627\u0646\u0627 \u0641\u064a \u0645\u0643\u0633\u064a\u0643\u0648 \u0633\u064a\u062a\u064a \u060c \u0627\u0644\u0645\u0643\u0633\u064a\u0643"},"content":{"rendered":"<div id=\"trave-794203041\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>\u062a\u0641\u0627\u0635\u064a\u0644 \u0642\u0646\u0635\u0644\u064a\u0629 \u0628\u0648\u062a\u0633\u0648\u0627\u0646\u0627 \u0641\u064a \u0645\u0643\u0633\u064a\u0643\u0648 \u0633\u064a\u062a\u064a \u060c \u0627\u0644\u0645\u0643\u0633\u064a\u0643<\/h3>\n<p><strong><br \/>\n\u0639\u0646\u0648\u0627\u0646:<\/strong><br \/>\nLomas de Chapultepec<br \/>\nDelegaci\u00f3n Hn Hidalgp<br \/>\nC.P.11000 \u060c \u0627\u0644\u0645\u0643\u0633\u064a\u0643 \u060c \u0645\u062f\u0627\u0641\u0639<br \/>\n\u0627\u0644\u0645\u0643\u0633\u064a\u0643<br \/>\n<strong><br \/>\n\u0633\u0641\u064a\u0631:<\/strong><br \/>\n<strong>\u0647\u0627\u062a\u0641:<\/strong> (+52) 55 5258-0311<br \/>\n<strong>\u0641\u0627\u0643\u0633:<\/strong> (+52) 55 5258-0308<br \/>\n<strong>\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong><br \/>\n<strong>\u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> <\/p>\n<p><strong>\u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/strong> <\/p>\n<div id=\"trave-2261269665\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u062a\u0641\u0627\u0635\u064a\u0644 \u0642\u0646\u0635\u0644\u064a\u0629 \u0628\u0648\u062a\u0633\u0648\u0627\u0646\u0627 \u0641\u064a \u0645\u0643\u0633\u064a\u0643\u0648 \u0633\u064a\u062a\u064a \u060c \u0627\u0644\u0645\u0643\u0633\u064a\u0643 \u0639\u0646\u0648\u0627\u0646: Lomas de Chapultepec Delegaci\u00f3n Hn Hidalgp C.P.11000 \u060c \u0627\u0644\u0645\u0643\u0633\u064a\u0643 \u060c \u0645\u062f\u0627\u0641\u0639 \u0627\u0644\u0645\u0643\u0633\u064a\u0643 \u0633\u0641\u064a\u0631: \u0647\u0627\u062a\u0641: (+52) 55 5258-0311 \u0641\u0627\u0643\u0633: (+52) 55 5258-0308 \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a: \u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a: \u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16555,13080,15589,15632],"tags":[12951],"class_list":["post-150001","post","type-post","status-publish","format-standard","hentry","category-16555","category-13080","category-15589","category-15632","tag-12951"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/150001"}],"collection":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/comments?post=150001"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/150001\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/media?parent=150001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/categories?post=150001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/tags?post=150001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}