{"id":148553,"date":"2019-09-01T15:18:02","date_gmt":"2019-09-01T15:18:02","guid":{"rendered":"https:\/\/travelqa.com\/%d8%b3%d9%81%d8%a7%d8%b1%d8%a9-%d8%aa%d8%b1%d9%83%d9%8a%d8%a7-%d9%81%d9%8a-%d8%a8%d9%8a%d8%b4%d9%83%d9%8a%d9%83-%d8%8c-%d9%82%d8%b1%d8%ba%d9%8a%d8%b2%d8%b3%d8%aa%d8%a7%d9%86\/"},"modified":"2019-09-01T15:18:02","modified_gmt":"2019-09-01T15:18:02","slug":"%d8%b3%d9%81%d8%a7%d8%b1%d8%a9-%d8%aa%d8%b1%d9%83%d9%8a%d8%a7-%d9%81%d9%8a-%d8%a8%d9%8a%d8%b4%d9%83%d9%8a%d9%83-%d8%8c-%d9%82%d8%b1%d8%ba%d9%8a%d8%b2%d8%b3%d8%aa%d8%a7%d9%86","status":"publish","type":"post","link":"https:\/\/travelqa.com\/ar\/%d8%b3%d9%81%d8%a7%d8%b1%d8%a9-%d8%aa%d8%b1%d9%83%d9%8a%d8%a7-%d9%81%d9%8a-%d8%a8%d9%8a%d8%b4%d9%83%d9%8a%d9%83-%d8%8c-%d9%82%d8%b1%d8%ba%d9%8a%d8%b2%d8%b3%d8%aa%d8%a7%d9%86\/","title":{"rendered":"\u0633\u0641\u0627\u0631\u0629 \u062a\u0631\u0643\u064a\u0627 \u0641\u064a \u0628\u064a\u0634\u0643\u064a\u0643 \u060c \u0642\u0631\u063a\u064a\u0632\u0633\u062a\u0627\u0646"},"content":{"rendered":"<div id=\"trave-261006064\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0633\u0641\u0627\u0631\u0629 \u0627\u0644\u062a\u0631\u0643\u064a\u0629 \u0641\u064a \u0628\u064a\u0634\u0643\u064a\u0643 \u060c \u0642\u0631\u063a\u064a\u0632\u0633\u062a\u0627\u0646<\/h3>\n<p><strong><br \/>\n\u0639\u0646\u0648\u0627\u0646:<\/strong><br \/>\n720040 \u0628\u064a\u0634\u0643\u064a\u0643<br \/>\n\u0642\u064a\u0631\u063a\u064a\u0632\u0633\u062a\u0627\u0646<br \/>\n<strong><br \/>\n\u0633\u0641\u064a\u0631:<\/strong> \u062c\u0646\u0643\u064a\u0632 \u0643\u0627\u0645\u0644 \u0641\u0631\u0627\u062a \u060c \u0627\u0644\u0633\u0641\u064a\u0631<br \/>\n<strong>\u0647\u0627\u062a\u0641:<\/strong> (+996) (312) 90 99 12<br \/>\n<strong>\u0641\u0627\u0643\u0633:<\/strong> (+996) (312) 90 99 12<br \/>\n<strong>\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong><br \/>\n<strong>\u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> <\/p>\n<p><strong>\u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/strong> 09.00 &#8211; 12.30 \u0648 14.00 &#8211; 18.00<\/p>\n<div id=\"trave-3782796017\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0633\u0641\u0627\u0631\u0629 \u0627\u0644\u062a\u0631\u0643\u064a\u0629 \u0641\u064a \u0628\u064a\u0634\u0643\u064a\u0643 \u060c \u0642\u0631\u063a\u064a\u0632\u0633\u062a\u0627\u0646 \u0639\u0646\u0648\u0627\u0646: 720040 \u0628\u064a\u0634\u0643\u064a\u0643 \u0642\u064a\u0631\u063a\u064a\u0632\u0633\u062a\u0627\u0646 \u0633\u0641\u064a\u0631: \u062c\u0646\u0643\u064a\u0632 \u0643\u0627\u0645\u0644 \u0641\u0631\u0627\u062a \u060c \u0627\u0644\u0633\u0641\u064a\u0631 \u0647\u0627\u062a\u0641: (+996) (312) 90 99 12 \u0641\u0627\u0643\u0633: (+996) (312) 90 99 12 \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a: \u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a: \u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644: 09.00 &#8211; 12.30 \u0648 14.00 &#8211; 18.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13018,16472,13017,13009],"tags":[12957],"class_list":["post-148553","post","type-post","status-publish","format-standard","hentry","category-13018","category-16472","category-13017","category-13009","tag-12957"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/148553"}],"collection":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/comments?post=148553"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/148553\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/media?parent=148553"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/categories?post=148553"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/tags?post=148553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}