{"id":147540,"date":"2019-09-01T15:05:18","date_gmt":"2019-09-01T15:05:18","guid":{"rendered":"https:\/\/travelqa.com\/%d8%b3%d9%81%d8%a7%d8%b1%d8%a9-%d8%a5%d9%8a%d8%b7%d8%a7%d9%84%d9%8a%d8%a7-%d9%81%d9%8a-%d8%b7%d9%88%d9%83%d9%8a%d9%88-%d8%a8%d8%a7%d9%84%d9%8a%d8%a7%d8%a8%d8%a7%d9%86\/"},"modified":"2019-09-01T15:05:18","modified_gmt":"2019-09-01T15:05:18","slug":"%d8%b3%d9%81%d8%a7%d8%b1%d8%a9-%d8%a5%d9%8a%d8%b7%d8%a7%d9%84%d9%8a%d8%a7-%d9%81%d9%8a-%d8%b7%d9%88%d9%83%d9%8a%d9%88-%d8%a8%d8%a7%d9%84%d9%8a%d8%a7%d8%a8%d8%a7%d9%86","status":"publish","type":"post","link":"https:\/\/travelqa.com\/ar\/%d8%b3%d9%81%d8%a7%d8%b1%d8%a9-%d8%a5%d9%8a%d8%b7%d8%a7%d9%84%d9%8a%d8%a7-%d9%81%d9%8a-%d8%b7%d9%88%d9%83%d9%8a%d9%88-%d8%a8%d8%a7%d9%84%d9%8a%d8%a7%d8%a8%d8%a7%d9%86\/","title":{"rendered":"\u0633\u0641\u0627\u0631\u0629 \u0625\u064a\u0637\u0627\u0644\u064a\u0627 \u0641\u064a \u0637\u0648\u0643\u064a\u0648 \u0628\u0627\u0644\u064a\u0627\u0628\u0627\u0646"},"content":{"rendered":"<div id=\"trave-3699515423\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0633\u0641\u0627\u0631\u0629 \u0627\u0644\u0625\u064a\u0637\u0627\u0644\u064a\u0629 \u0641\u064a \u0637\u0648\u0643\u064a\u0648 \u060c \u0627\u0644\u064a\u0627\u0628\u0627\u0646<\/h3>\n<p><strong><br \/>\n\u0639\u0646\u0648\u0627\u0646:<\/strong><br \/>\n\u0637\u0648\u0643\u064a\u0648 108-8302<br \/>\n\u0627\u0644\u064a\u0627\u0628\u0627\u0646<br \/>\n<strong><br \/>\n\u0633\u0641\u064a\u0631:<\/strong><br \/>\n<strong>\u0647\u0627\u062a\u0641:<\/strong> (+81) 3 3453 5291<br \/>\n<strong>\u0641\u0627\u0643\u0633:<\/strong> (+81) 3 3456 2319<br \/>\n<strong>\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong><br \/>\n<strong>\u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> <\/p>\n<p><strong>\u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/strong> <\/p>\n<div id=\"trave-251801503\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0633\u0641\u0627\u0631\u0629 \u0627\u0644\u0625\u064a\u0637\u0627\u0644\u064a\u0629 \u0641\u064a \u0637\u0648\u0643\u064a\u0648 \u060c \u0627\u0644\u064a\u0627\u0628\u0627\u0646 \u0639\u0646\u0648\u0627\u0646: \u0637\u0648\u0643\u064a\u0648 108-8302 \u0627\u0644\u064a\u0627\u0628\u0627\u0646 \u0633\u0641\u064a\u0631: \u0647\u0627\u062a\u0641: (+81) 3 3453 5291 \u0641\u0627\u0643\u0633: (+81) 3 3456 2319 \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a: \u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a: \u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13088,13089,16420,12955],"tags":[12957],"class_list":["post-147540","post","type-post","status-publish","format-standard","hentry","category-13088","category-13089","category-16420","category-12955","tag-12957"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/147540"}],"collection":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/comments?post=147540"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/147540\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/media?parent=147540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/categories?post=147540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/tags?post=147540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}