{"id":146488,"date":"2019-09-01T14:55:31","date_gmt":"2019-09-01T14:55:31","guid":{"rendered":"https:\/\/travelqa.com\/%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%b3%d9%88%d9%8a%d8%b3%d8%b1%d8%a7-%d9%81%d9%8a-%d8%ad%d9%8a%d9%81%d8%a7%d8%8c-%d8%a5%d8%b3%d8%b1%d8%a7%d8%a6%d9%8a%d9%84\/"},"modified":"2019-09-01T14:55:31","modified_gmt":"2019-09-01T14:55:31","slug":"%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%b3%d9%88%d9%8a%d8%b3%d8%b1%d8%a7-%d9%81%d9%8a-%d8%ad%d9%8a%d9%81%d8%a7%d8%8c-%d8%a5%d8%b3%d8%b1%d8%a7%d8%a6%d9%8a%d9%84","status":"publish","type":"post","link":"https:\/\/travelqa.com\/ar\/%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%b3%d9%88%d9%8a%d8%b3%d8%b1%d8%a7-%d9%81%d9%8a-%d8%ad%d9%8a%d9%81%d8%a7%d8%8c-%d8%a5%d8%b3%d8%b1%d8%a7%d8%a6%d9%8a%d9%84\/","title":{"rendered":"\u0642\u0646\u0635\u0644\u064a\u0629 \u0633\u0648\u064a\u0633\u0631\u0627 \u0641\u064a \u062d\u064a\u0641\u0627\u060c \u0625\u0633\u0631\u0627\u0626\u064a\u0644"},"content":{"rendered":"<div id=\"trave-1507244342\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u0633\u0648\u064a\u0633\u0631\u064a\u0629 \u0641\u064a \u062d\u064a\u0641\u0627 \u060c \u0625\u0633\u0631\u0627\u0626\u064a\u0644<\/h3>\n<p><strong><br \/>\n\u0639\u0646\u0648\u0627\u0646:<\/strong><br \/>\n98 Hanassi Avenue<br \/>\nP.O.\u0645\u0631\u0628\u0639 6240<br \/>\n31061 \u062d\u064a\u0641\u0627<br \/>\n\u0625\u0633\u0631\u0627\u0626\u064a\u0644<br \/>\n<strong><br \/>\n\u0633\u0641\u064a\u0631:<\/strong> \u0627\u0644\u0633\u064a\u062f \u0645\u0627\u064a\u0643\u0644 \u0628\u0627\u0628\u064a \u060c \u0627\u0644\u0642\u0646\u0635\u0644 \u0627\u0644\u0641\u062e\u0631\u064a<br \/>\n<strong>\u0647\u0627\u062a\u0641:<\/strong> (+972) 4 838 14 08<br \/>\n<strong>\u0641\u0627\u0643\u0633:<\/strong> (+972) 4 837 13 53<br \/>\n<strong>\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> haifa@honrep.ch<br \/>\n<strong>\u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> <\/p>\n<p><strong>\u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/strong> <\/p>\n<div id=\"trave-1610476558\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u0633\u0648\u064a\u0633\u0631\u064a\u0629 \u0641\u064a \u062d\u064a\u0641\u0627 \u060c \u0625\u0633\u0631\u0627\u0626\u064a\u0644 \u0639\u0646\u0648\u0627\u0646: 98 Hanassi Avenue P.O.\u0645\u0631\u0628\u0639 6240 31061 \u062d\u064a\u0641\u0627 \u0625\u0633\u0631\u0627\u0626\u064a\u0644 \u0633\u0641\u064a\u0631: \u0627\u0644\u0633\u064a\u062f \u0645\u0627\u064a\u0643\u0644 \u0628\u0627\u0628\u064a \u060c \u0627\u0644\u0642\u0646\u0635\u0644 \u0627\u0644\u0641\u062e\u0631\u064a \u0647\u0627\u062a\u0641: (+972) 4 838 14 08 \u0641\u0627\u0643\u0633: (+972) 4 837 13 53 \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a: haifa@honrep.ch \u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a: \u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13120,15419,16393,13093],"tags":[12951],"class_list":["post-146488","post","type-post","status-publish","format-standard","hentry","category-13120","category-15419","category-16393","category-13093","tag-12951"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/146488"}],"collection":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/comments?post=146488"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/146488\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/media?parent=146488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/categories?post=146488"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/tags?post=146488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}