{"id":146414,"date":"2019-09-01T14:54:46","date_gmt":"2019-09-01T14:54:46","guid":{"rendered":"https:\/\/travelqa.com\/%d8%b3%d9%81%d8%a7%d8%b1%d8%a9-%d9%83%d9%8a%d9%86%d9%8a%d8%a7-%d9%81%d9%8a-%d8%af%d8%a8%d9%84%d9%86-%d8%8c-%d8%a3%d9%8a%d8%b1%d9%84%d9%86%d8%af%d8%a7\/"},"modified":"2019-09-01T14:54:46","modified_gmt":"2019-09-01T14:54:46","slug":"%d8%b3%d9%81%d8%a7%d8%b1%d8%a9-%d9%83%d9%8a%d9%86%d9%8a%d8%a7-%d9%81%d9%8a-%d8%af%d8%a8%d9%84%d9%86-%d8%8c-%d8%a3%d9%8a%d8%b1%d9%84%d9%86%d8%af%d8%a7","status":"publish","type":"post","link":"https:\/\/travelqa.com\/ar\/%d8%b3%d9%81%d8%a7%d8%b1%d8%a9-%d9%83%d9%8a%d9%86%d9%8a%d8%a7-%d9%81%d9%8a-%d8%af%d8%a8%d9%84%d9%86-%d8%8c-%d8%a3%d9%8a%d8%b1%d9%84%d9%86%d8%af%d8%a7\/","title":{"rendered":"\u0633\u0641\u0627\u0631\u0629 \u0643\u064a\u0646\u064a\u0627 \u0641\u064a \u062f\u0628\u0644\u0646 \u060c \u0623\u064a\u0631\u0644\u0646\u062f\u0627"},"content":{"rendered":"<div id=\"trave-1034141307\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0633\u0641\u0627\u0631\u0629 \u0627\u0644\u0643\u064a\u0646\u064a\u0629 \u0641\u064a \u062f\u0628\u0644\u0646 \u060c \u0623\u064a\u0631\u0644\u0646\u062f\u0627<\/h3>\n<p><strong><br \/>\n\u0639\u0646\u0648\u0627\u0646:<\/strong><br \/>\n\u0628\u0648\u0644\u0632\u0628\u0631\u064a\u062f\u062c<br \/>\n\u062f\u0628\u0644\u0646 4<br \/>\n\u0623\u064a\u0631\u0644\u0646\u062f\u0627<br \/>\n<strong><br \/>\n\u0633\u0641\u064a\u0631:<\/strong> \u0627\u0644\u0633\u064a\u062f \u0631\u064a\u062a\u0634\u0627\u0631\u062f \u0623\u0646\u062c\u0648\u0644\u0648 \u0623\u0648\u0628\u064a\u0628\u064a \u060c \u0627\u0644\u0633\u0641\u064a\u0631<br \/>\n<strong>\u0647\u0627\u062a\u0641:<\/strong> (+353) 1 668 5506<br \/>\n<strong>\u0641\u0627\u0643\u0633:<\/strong> (+353) 1 668 5506<br \/>\n<strong>\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong><br \/>\n<strong>\u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> <\/p>\n<p><strong>\u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/strong> <\/p>\n<div id=\"trave-1673170641\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0633\u0641\u0627\u0631\u0629 \u0627\u0644\u0643\u064a\u0646\u064a\u0629 \u0641\u064a \u062f\u0628\u0644\u0646 \u060c \u0623\u064a\u0631\u0644\u0646\u062f\u0627 \u0639\u0646\u0648\u0627\u0646: \u0628\u0648\u0644\u0632\u0628\u0631\u064a\u062f\u062c \u062f\u0628\u0644\u0646 4 \u0623\u064a\u0631\u0644\u0646\u062f\u0627 \u0633\u0641\u064a\u0631: \u0627\u0644\u0633\u064a\u062f \u0631\u064a\u062a\u0634\u0627\u0631\u062f \u0623\u0646\u062c\u0648\u0644\u0648 \u0623\u0648\u0628\u064a\u0628\u064a \u060c \u0627\u0644\u0633\u0641\u064a\u0631 \u0647\u0627\u062a\u0641: (+353) 1 668 5506 \u0641\u0627\u0643\u0633: (+353) 1 668 5506 \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a: \u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a: \u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15441,15292,16385,15291],"tags":[12957],"class_list":["post-146414","post","type-post","status-publish","format-standard","hentry","category-15441","category-15292","category-16385","category-15291","tag-12957"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/146414"}],"collection":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/comments?post=146414"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/146414\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/media?parent=146414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/categories?post=146414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/tags?post=146414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}