{"id":146010,"date":"2019-09-01T14:50:34","date_gmt":"2019-09-01T14:50:34","guid":{"rendered":"https:\/\/travelqa.com\/%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d9%85%d8%a7%d9%84%d9%8a%d8%b2%d9%8a%d8%a7-%d9%81%d9%8a-%d8%a8%d9%88%d9%86%d8%aa%d9%8a%d8%a7%d9%86%d8%a7%d9%83-%d8%8c-%d8%a7%d9%86%d8%af%d9%88%d9%86%d9%8a%d8%b3\/"},"modified":"2019-09-01T14:50:34","modified_gmt":"2019-09-01T14:50:34","slug":"%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d9%85%d8%a7%d9%84%d9%8a%d8%b2%d9%8a%d8%a7-%d9%81%d9%8a-%d8%a8%d9%88%d9%86%d8%aa%d9%8a%d8%a7%d9%86%d8%a7%d9%83-%d8%8c-%d8%a7%d9%86%d8%af%d9%88%d9%86%d9%8a%d8%b3","status":"publish","type":"post","link":"https:\/\/travelqa.com\/ar\/%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d9%85%d8%a7%d9%84%d9%8a%d8%b2%d9%8a%d8%a7-%d9%81%d9%8a-%d8%a8%d9%88%d9%86%d8%aa%d9%8a%d8%a7%d9%86%d8%a7%d9%83-%d8%8c-%d8%a7%d9%86%d8%af%d9%88%d9%86%d9%8a%d8%b3\/","title":{"rendered":"\u0642\u0646\u0635\u0644\u064a\u0629 \u0645\u0627\u0644\u064a\u0632\u064a\u0627 \u0641\u064a \u0628\u0648\u0646\u062a\u064a\u0627\u0646\u0627\u0643 \u060c \u0627\u0646\u062f\u0648\u0646\u064a\u0633\u064a\u0627"},"content":{"rendered":"<div id=\"trave-820843724\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>\u0627\u0644\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u0645\u0627\u0644\u064a\u0632\u064a\u0629 \u0627\u0644\u062a\u0641\u0627\u0635\u064a\u0644 \u0641\u064a \u0628\u0648\u0646\u062a\u064a\u0627\u0646\u0627\u0643 \u060c \u0627\u0646\u062f\u0648\u0646\u064a\u0633\u064a\u0627<\/h3>\n<p><strong><br \/>\n\u0639\u0646\u0648\u0627\u0646:<\/strong><br \/>\n\u0628\u0648\u0646\u062a\u064a\u0627\u0646\u0627\u0643 78124 \u060c \u0643\u0627\u0644\u064a\u0645\u0627\u0646\u062a\u0627\u0646 \u0628\u0627\u0631\u0627\u062a<br \/>\n\u0625\u0646\u062f\u0648\u0646\u064a\u0633\u064a\u0627<br \/>\n<strong><br \/>\n\u0633\u0641\u064a\u0631:<\/strong> Encik \u0645\u062d\u064a \u0627\u0644\u062f\u064a\u0646 \u0627\u0644\u063a\u0632\u0627\u0644\u064a \u060c \u0627\u0644\u0642\u0646\u0635\u0644<br \/>\n<strong>\u0647\u0627\u062a\u0641:<\/strong> (+62) (561) 736 060<br \/>\n<strong>\u0641\u0627\u0643\u0633:<\/strong> (+62) (561) 736 060<br \/>\n<strong>\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong><br \/>\n<strong>\u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> <\/p>\n<p><strong>\u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/strong> <\/p>\n<div id=\"trave-4033104281\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0627\u0644\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u0645\u0627\u0644\u064a\u0632\u064a\u0629 \u0627\u0644\u062a\u0641\u0627\u0635\u064a\u0644 \u0641\u064a \u0628\u0648\u0646\u062a\u064a\u0627\u0646\u0627\u0643 \u060c \u0627\u0646\u062f\u0648\u0646\u064a\u0633\u064a\u0627 \u0639\u0646\u0648\u0627\u0646: \u0628\u0648\u0646\u062a\u064a\u0627\u0646\u0627\u0643 78124 \u060c \u0643\u0627\u0644\u064a\u0645\u0627\u0646\u062a\u0627\u0646 \u0628\u0627\u0631\u0627\u062a \u0625\u0646\u062f\u0648\u0646\u064a\u0633\u064a\u0627 \u0633\u0641\u064a\u0631: Encik \u0645\u062d\u064a \u0627\u0644\u062f\u064a\u0646 \u0627\u0644\u063a\u0632\u0627\u0644\u064a \u060c \u0627\u0644\u0642\u0646\u0635\u0644 \u0647\u0627\u062a\u0641: (+62) (561) 736 060 \u0641\u0627\u0643\u0633: (+62) (561) 736 060 \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a: \u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a: \u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13116,13318,16358,13317],"tags":[12951],"class_list":["post-146010","post","type-post","status-publish","format-standard","hentry","category-13116","category-13318","category-16358","category-13317","tag-12951"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/146010"}],"collection":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/comments?post=146010"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/146010\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/media?parent=146010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/categories?post=146010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/tags?post=146010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}