{"id":145613,"date":"2019-09-01T14:46:45","date_gmt":"2019-09-01T14:46:45","guid":{"rendered":"https:\/\/travelqa.com\/%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%a3%d9%8a%d8%b1%d9%84%d9%86%d8%af%d8%a7-%d9%81%d9%8a-%d8%a8%d9%86%d8%ba%d8%a7%d9%84%d9%88%d8%b1-%d8%8c-%d8%a7%d9%84%d9%87%d9%86%d8%af\/"},"modified":"2019-09-01T14:46:45","modified_gmt":"2019-09-01T14:46:45","slug":"%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%a3%d9%8a%d8%b1%d9%84%d9%86%d8%af%d8%a7-%d9%81%d9%8a-%d8%a8%d9%86%d8%ba%d8%a7%d9%84%d9%88%d8%b1-%d8%8c-%d8%a7%d9%84%d9%87%d9%86%d8%af","status":"publish","type":"post","link":"https:\/\/travelqa.com\/ar\/%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%a3%d9%8a%d8%b1%d9%84%d9%86%d8%af%d8%a7-%d9%81%d9%8a-%d8%a8%d9%86%d8%ba%d8%a7%d9%84%d9%88%d8%b1-%d8%8c-%d8%a7%d9%84%d9%87%d9%86%d8%af\/","title":{"rendered":"\u0642\u0646\u0635\u0644\u064a\u0629 \u0623\u064a\u0631\u0644\u0646\u062f\u0627 \u0641\u064a \u0628\u0646\u063a\u0627\u0644\u0648\u0631 \u060c \u0627\u0644\u0647\u0646\u062f"},"content":{"rendered":"<div id=\"trave-2130910478\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u0625\u064a\u0631\u0644\u0646\u062f\u064a\u0629 \u0641\u064a \u0628\u0646\u063a\u0627\u0644\u0648\u0631 \u060c \u0627\u0644\u0647\u0646\u062f<\/h3>\n<p><strong><br \/>\n\u0639\u0646\u0648\u0627\u0646:<\/strong><br \/>\nc \/ o Biocon Limited<br \/>\n20th KM.Hosur Road<br \/>\nElectronics City PO<br \/>\nBangalore 560 100<br \/>\nIndia<br \/>\n<strong><br \/>\n\u0633\u0641\u064a\u0631:<\/strong> \u0627\u0644\u062f\u0643\u062a\u0648\u0631 \u0643\u064a\u0631\u0627\u0646 \u0645\u0627\u0632\u0648\u0645\u062f\u0627\u0631 \u0634\u0648 \u060c \u0627\u0644\u0642\u0646\u0635\u0644 \u0627\u0644\u0641\u062e\u0631\u064a<br \/>\n<strong>\u0647\u0627\u062a\u0641:<\/strong> (+91) 80 2808 2006<br \/>\n<strong>\u0641\u0627\u0643\u0633:<\/strong> (+91) 80 2852 1660<br \/>\n<strong>\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> karthik.vedanayagam@biocon.com<br \/>\n<strong>\u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> <\/p>\n<p><strong>\u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/strong> 09.30-17.00<\/p>\n<div id=\"trave-1648175614\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u0625\u064a\u0631\u0644\u0646\u062f\u064a\u0629 \u0641\u064a \u0628\u0646\u063a\u0627\u0644\u0648\u0631 \u060c \u0627\u0644\u0647\u0646\u062f \u0639\u0646\u0648\u0627\u0646: c \/ o Biocon Limited 20th KM.Hosur Road Electronics City PO Bangalore 560 100 India \u0633\u0641\u064a\u0631: \u0627\u0644\u062f\u0643\u062a\u0648\u0631 \u0643\u064a\u0631\u0627\u0646 \u0645\u0627\u0632\u0648\u0645\u062f\u0627\u0631 \u0634\u0648 \u060c \u0627\u0644\u0642\u0646\u0635\u0644 \u0627\u0644\u0641\u062e\u0631\u064a \u0647\u0627\u062a\u0641: (+91) 80 2808 2006 \u0641\u0627\u0643\u0633: (+91) 80 2852 1660 \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a: karthik.vedanayagam@biocon.com \u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a: \u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644: 09.30-17.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15441,15562,16337,13314],"tags":[12951],"class_list":["post-145613","post","type-post","status-publish","format-standard","hentry","category-15441","category-15562","category-16337","category-13314","tag-12951"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/145613"}],"collection":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/comments?post=145613"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/145613\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/media?parent=145613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/categories?post=145613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/tags?post=145613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}