{"id":141780,"date":"2019-09-01T14:00:06","date_gmt":"2019-09-01T14:00:06","guid":{"rendered":"https:\/\/travelqa.com\/%d8%a7%d9%84%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%a7%d9%84%d8%b9%d8%a7%d9%85%d8%a9-%d9%84%d8%a8%d9%8a%d8%b1%d9%88-%d9%81%d9%8a-%d8%ba%d9%88%d8%a7%d9%8a%d8%a7%d9%83%d9%8a%d9%84-%d8%8c-%d8%a7%d9%84\/"},"modified":"2019-09-01T14:00:06","modified_gmt":"2019-09-01T14:00:06","slug":"%d8%a7%d9%84%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%a7%d9%84%d8%b9%d8%a7%d9%85%d8%a9-%d9%84%d8%a8%d9%8a%d8%b1%d9%88-%d9%81%d9%8a-%d8%ba%d9%88%d8%a7%d9%8a%d8%a7%d9%83%d9%8a%d9%84-%d8%8c-%d8%a7%d9%84","status":"publish","type":"post","link":"https:\/\/travelqa.com\/ar\/%d8%a7%d9%84%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%a7%d9%84%d8%b9%d8%a7%d9%85%d8%a9-%d9%84%d8%a8%d9%8a%d8%b1%d9%88-%d9%81%d9%8a-%d8%ba%d9%88%d8%a7%d9%8a%d8%a7%d9%83%d9%8a%d9%84-%d8%8c-%d8%a7%d9%84\/","title":{"rendered":"\u0627\u0644\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u0639\u0627\u0645\u0629 \u0644\u0628\u064a\u0631\u0648 \u0641\u064a \u063a\u0648\u0627\u064a\u0627\u0643\u064a\u0644 \u060c \u0627\u0644\u0625\u0643\u0648\u0627\u062f\u0648\u0631"},"content":{"rendered":"<div id=\"trave-4016817823\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>\u0627\u0644\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u0628\u064a\u0631\u0648\u0641\u064a\u0629 \u0627\u0644\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0639\u0627\u0645\u0629 \u0641\u064a \u063a\u0648\u0627\u064a\u0627\u0643\u064a\u0644 \u060c \u0627\u0644\u0625\u0643\u0648\u0627\u062f\u0648\u0631<\/h3>\n<p><strong><br \/>\n\u0639\u0646\u0648\u0627\u0646:<\/strong><br \/>\nPiso 13\u060c Edificio Centrum<br \/>\nKennedy Norte<br \/>\nGuayaquil<br \/>\nEcuador<br \/>\n<strong><br \/>\n\u0633\u0641\u064a\u0631:<\/strong> \u0627\u0644\u0633\u064a\u062f Hugo Pereyra Plasecia \u060c \u0627\u0644\u0642\u0646\u0635\u0644 \u0627\u0644\u0639\u0627\u0645<br \/>\n<strong>\u0647\u0627\u062a\u0641:<\/strong> (+593) (4) 263 4035<br \/>\n<strong>\u0641\u0627\u0643\u0633:<\/strong><br \/>\n<strong>\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong><br \/>\n<strong>\u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> <\/p>\n<p><strong>\u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/strong> 09.30 &#8211; 13.00 \u0648 15.00 &#8211; 17.00<\/p>\n<div id=\"trave-3433038620\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0627\u0644\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u0628\u064a\u0631\u0648\u0641\u064a\u0629 \u0627\u0644\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0639\u0627\u0645\u0629 \u0641\u064a \u063a\u0648\u0627\u064a\u0627\u0643\u064a\u0644 \u060c \u0627\u0644\u0625\u0643\u0648\u0627\u062f\u0648\u0631 \u0639\u0646\u0648\u0627\u0646: Piso 13\u060c Edificio Centrum Kennedy Norte Guayaquil Ecuador \u0633\u0641\u064a\u0631: \u0627\u0644\u0633\u064a\u062f Hugo Pereyra Plasecia \u060c \u0627\u0644\u0642\u0646\u0635\u0644 \u0627\u0644\u0639\u0627\u0645 \u0647\u0627\u062a\u0641: (+593) (4) 263 4035 \u0641\u0627\u0643\u0633: \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a: \u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a: \u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644: 09.30 &#8211; 13.00 \u0648 15.00 &#8211; 17.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15302,16122,15456,13405],"tags":[12962],"class_list":["post-141780","post","type-post","status-publish","format-standard","hentry","category-15302","category-16122","category-15456","category-13405","tag-12962"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/141780"}],"collection":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/comments?post=141780"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/141780\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/media?parent=141780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/categories?post=141780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/tags?post=141780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}