{"id":141660,"date":"2019-09-01T13:58:34","date_gmt":"2019-09-01T13:58:34","guid":{"rendered":"https:\/\/travelqa.com\/%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d9%85-%d9%85%d9%88%d9%86%d8%a7%d9%83%d9%88-%d9%81%d9%8a-%d8%ba%d9%88%d8%a7%d9%8a%d8%a7%d9%83%d9%8a%d9%84%d8%8c-%d8%a7%d9%84%d8%a5%d9%83%d9%88%d8%a7%d8%af%d9%88\/"},"modified":"2019-09-01T13:58:34","modified_gmt":"2019-09-01T13:58:34","slug":"%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d9%85-%d9%85%d9%88%d9%86%d8%a7%d9%83%d9%88-%d9%81%d9%8a-%d8%ba%d9%88%d8%a7%d9%8a%d8%a7%d9%83%d9%8a%d9%84%d8%8c-%d8%a7%d9%84%d8%a5%d9%83%d9%88%d8%a7%d8%af%d9%88","status":"publish","type":"post","link":"https:\/\/travelqa.com\/ar\/%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d9%85-%d9%85%d9%88%d9%86%d8%a7%d9%83%d9%88-%d9%81%d9%8a-%d8%ba%d9%88%d8%a7%d9%8a%d8%a7%d9%83%d9%8a%d9%84%d8%8c-%d8%a7%d9%84%d8%a5%d9%83%d9%88%d8%a7%d8%af%d9%88\/","title":{"rendered":"\u0642\u0646\u0635\u0644\u064a\u0629 \u0645 \u0645\u0648\u0646\u0627\u0643\u0648 \u0641\u064a \u063a\u0648\u0627\u064a\u0627\u0643\u064a\u0644\u060c \u0627\u0644\u0625\u0643\u0648\u0627\u062f\u0648\u0631"},"content":{"rendered":"<div id=\"trave-220463925\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>\u062a\u0641\u0627\u0635\u064a\u0644 \u0642\u0646\u0635\u0644\u064a\u0629 \u0645\u0648\u0646\u0627\u0643\u0648 \u0641\u064a \u063a\u0648\u0627\u064a\u0627\u0643\u064a\u0644 \u060c \u0627\u0644\u0625\u0643\u0648\u0627\u062f\u0648\u0631<\/h3>\n<p><strong><br \/>\n\u0639\u0646\u0648\u0627\u0646:<\/strong><br \/>\nAvenida 9 de Octubre 516 y Escobedo (Esquina)<br \/>\nCasilla postal 776<br \/>\nGuayaquil<br \/>\nEcuador<br \/>\n<strong><br \/>\n\u0633\u0641\u064a\u0631:<\/strong> \u0627\u0644\u0633\u064a\u062f \u062e\u0627\u0641\u064a\u064a\u0631 \u062a\u0648\u0644\u0627 \u0646\u064a\u0631\u0627 \u060c \u0627\u0644\u0642\u0646\u0635\u0644 \u0627\u0644\u0641\u062e\u0631\u064a<br \/>\n<strong>\u0647\u0627\u062a\u0641:<\/strong> (+593) (4) 230 6606<br \/>\n<strong>\u0641\u0627\u0643\u0633:<\/strong> (+593) (4) 256 6723<br \/>\n<strong>\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> consuladomonacoguyaquil@yahoo.com<br \/>\njtola@gye.satnet.net<br \/>\n<strong>\u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> <\/p>\n<p><strong>\u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/strong> <\/p>\n<div id=\"trave-953948477\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u062a\u0641\u0627\u0635\u064a\u0644 \u0642\u0646\u0635\u0644\u064a\u0629 \u0645\u0648\u0646\u0627\u0643\u0648 \u0641\u064a \u063a\u0648\u0627\u064a\u0627\u0643\u064a\u0644 \u060c \u0627\u0644\u0625\u0643\u0648\u0627\u062f\u0648\u0631 \u0639\u0646\u0648\u0627\u0646: Avenida 9 de Octubre 516 y Escobedo (Esquina) Casilla postal 776 Guayaquil Ecuador \u0633\u0641\u064a\u0631: \u0627\u0644\u0633\u064a\u062f \u062e\u0627\u0641\u064a\u064a\u0631 \u062a\u0648\u0644\u0627 \u0646\u064a\u0631\u0627 \u060c \u0627\u0644\u0642\u0646\u0635\u0644 \u0627\u0644\u0641\u062e\u0631\u064a \u0647\u0627\u062a\u0641: (+593) (4) 230 6606 \u0641\u0627\u0643\u0633: (+593) (4) 256 6723 \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a: consuladomonacoguyaquil@yahoo.com jtola@gye.satnet.net \u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a: \u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15302,16121,15388,15387],"tags":[12951],"class_list":["post-141660","post","type-post","status-publish","format-standard","hentry","category-15302","category-16121","category-15388","category-15387","tag-12951"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/141660"}],"collection":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/comments?post=141660"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/141660\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/media?parent=141660"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/categories?post=141660"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/tags?post=141660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}