{"id":139846,"date":"2019-09-01T13:35:42","date_gmt":"2019-09-01T13:35:42","guid":{"rendered":"https:\/\/travelqa.com\/%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%a3%d8%b3%d8%a8%d8%a7%d9%86%d9%8a%d8%a7-%d9%81%d9%8a-%d9%83%d9%88%d9%86%d8%b3%d8%a8%d8%b3%d9%8a%d9%88%d9%86-%d8%8c-%d8%aa%d8%b4%d9%8a%d9%84%d9%8a\/"},"modified":"2019-09-01T13:35:42","modified_gmt":"2019-09-01T13:35:42","slug":"%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%a3%d8%b3%d8%a8%d8%a7%d9%86%d9%8a%d8%a7-%d9%81%d9%8a-%d9%83%d9%88%d9%86%d8%b3%d8%a8%d8%b3%d9%8a%d9%88%d9%86-%d8%8c-%d8%aa%d8%b4%d9%8a%d9%84%d9%8a","status":"publish","type":"post","link":"https:\/\/travelqa.com\/ar\/%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%a3%d8%b3%d8%a8%d8%a7%d9%86%d9%8a%d8%a7-%d9%81%d9%8a-%d9%83%d9%88%d9%86%d8%b3%d8%a8%d8%b3%d9%8a%d9%88%d9%86-%d8%8c-%d8%aa%d8%b4%d9%8a%d9%84%d9%8a\/","title":{"rendered":"\u0642\u0646\u0635\u0644\u064a\u0629 \u0623\u0633\u0628\u0627\u0646\u064a\u0627 \u0641\u064a \u0643\u0648\u0646\u0633\u0628\u0633\u064a\u0648\u0646 \u060c \u062a\u0634\u064a\u0644\u064a"},"content":{"rendered":"<div id=\"trave-1163405074\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u0625\u0633\u0628\u0627\u0646\u064a\u0629 \u0641\u064a \u0643\u0648\u0646\u0633\u064a\u0628\u0633\u064a\u0627\u0646 \u060c \u062a\u0634\u064a\u0644\u064a<\/h3>\n<p><strong><br \/>\n\u0639\u0646\u0648\u0627\u0646:<\/strong><br \/>\nBarros Arana 675 \u060c \u0627\u0644\u0637\u0627\u0628\u0642 2<br \/>\nCasilla 1327<br \/>\nConcepci\u00c3\u00b3n<br \/>\n\u0634\u064a\u0644\u064a<br \/>\n<strong><br \/>\n\u0633\u0641\u064a\u0631:<\/strong> \u062e\u0648\u0627\u0646 \u0641\u0631\u0627\u0646\u0633\u064a\u0633\u0643\u0648 \u0641\u064a\u0644\u0627\u0646\u0648\u064a\u0641\u0627 \u0645\u062f\u064a\u0646\u0627 \u060c \u0627\u0644\u0642\u0646\u0635\u0644 \u0627\u0644\u0641\u062e\u0631\u064a<br \/>\n<strong>\u0647\u0627\u062a\u0641:<\/strong> (+56) (41) 222 4249<br \/>\n(+56) (41) 221 4954<br \/>\n<strong>\u0641\u0627\u0643\u0633:<\/strong> (+56) (41) 291 0189<br \/>\n<strong>\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> chespana.concepcion@gmail.com<br \/>\nccespanaconce@gmail.com<br \/>\nccespanol@tie.cl<br \/>\n<strong>\u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> <\/p>\n<p><strong>\u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/strong> <\/p>\n<div id=\"trave-496555155\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u0625\u0633\u0628\u0627\u0646\u064a\u0629 \u0641\u064a \u0643\u0648\u0646\u0633\u064a\u0628\u0633\u064a\u0627\u0646 \u060c \u062a\u0634\u064a\u0644\u064a \u0639\u0646\u0648\u0627\u0646: Barros Arana 675 \u060c \u0627\u0644\u0637\u0627\u0628\u0642 2 Casilla 1327 Concepci\u00c3\u00b3n \u0634\u064a\u0644\u064a \u0633\u0641\u064a\u0631: \u062e\u0648\u0627\u0646 \u0641\u0631\u0627\u0646\u0633\u064a\u0633\u0643\u0648 \u0641\u064a\u0644\u0627\u0646\u0648\u064a\u0641\u0627 \u0645\u062f\u064a\u0646\u0627 \u060c \u0627\u0644\u0642\u0646\u0635\u0644 \u0627\u0644\u0641\u062e\u0631\u064a \u0647\u0627\u062a\u0641: (+56) (41) 222 4249 (+56) (41) 221 4954 \u0641\u0627\u0643\u0633: (+56) (41) 291 0189 \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a: chespana.concepcion@gmail.com ccespanaconce@gmail.com ccespanol@tie.cl \u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a: \u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13200,15383,15992,15311],"tags":[12951],"class_list":["post-139846","post","type-post","status-publish","format-standard","hentry","category-13200","category-15383","category-15992","category-15311","tag-12951"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/139846"}],"collection":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/comments?post=139846"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/139846\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/media?parent=139846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/categories?post=139846"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/tags?post=139846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}