{"id":139070,"date":"2019-09-01T13:27:53","date_gmt":"2019-09-01T13:27:53","guid":{"rendered":"https:\/\/travelqa.com\/%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%b3%d9%8a%d8%b4%d9%84-%d9%81%d9%8a-%d8%aa%d9%88%d8%b1%d9%88%d9%86%d8%aa%d9%88-%d8%8c-%d9%83%d9%86%d8%af%d8%a7\/"},"modified":"2019-09-01T13:27:53","modified_gmt":"2019-09-01T13:27:53","slug":"%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%b3%d9%8a%d8%b4%d9%84-%d9%81%d9%8a-%d8%aa%d9%88%d8%b1%d9%88%d9%86%d8%aa%d9%88-%d8%8c-%d9%83%d9%86%d8%af%d8%a7","status":"publish","type":"post","link":"https:\/\/travelqa.com\/ar\/%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%b3%d9%8a%d8%b4%d9%84-%d9%81%d9%8a-%d8%aa%d9%88%d8%b1%d9%88%d9%86%d8%aa%d9%88-%d8%8c-%d9%83%d9%86%d8%af%d8%a7\/","title":{"rendered":"\u0642\u0646\u0635\u0644\u064a\u0629 \u0633\u064a\u0634\u0644 \u0641\u064a \u062a\u0648\u0631\u0648\u0646\u062a\u0648 \u060c \u0643\u0646\u062f\u0627"},"content":{"rendered":"<div id=\"trave-179537345\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u0633\u064a\u0634\u064a\u0644\u064a\u0629 \u0641\u064a \u062a\u0648\u0631\u0646\u062a\u0648 \u060c \u0643\u0646\u062f\u0627<\/h3>\n<p><strong><br \/>\n\u0639\u0646\u0648\u0627\u0646:<\/strong><br \/>\n18 Doon Road<br \/>\nToronto\u060c ON M2L IL9<br \/>\nCanada<br \/>\n<strong><br \/>\n\u0633\u0641\u064a\u0631:<\/strong> \u0633\u062a\u064a\u0648\u0627\u0631\u062a \u0645\u064a\u0644\u0631 \u060c \u0627\u0644\u0642\u0646\u0635\u0644 \u0627\u0644\u0641\u062e\u0631\u064a<br \/>\n<strong>\u0647\u0627\u062a\u0641:<\/strong> (+1) 416-256-1947<br \/>\n<strong>\u0641\u0627\u0643\u0633:<\/strong><br \/>\n<strong>\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> stumiller@rogers.com<br \/>\nsmiller@rogers.com<br \/>\n<strong>\u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> <\/p>\n<p><strong>\u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/strong> <\/p>\n<div id=\"trave-1785303228\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u0633\u064a\u0634\u064a\u0644\u064a\u0629 \u0641\u064a \u062a\u0648\u0631\u0646\u062a\u0648 \u060c \u0643\u0646\u062f\u0627 \u0639\u0646\u0648\u0627\u0646: 18 Doon Road Toronto\u060c ON M2L IL9 Canada \u0633\u0641\u064a\u0631: \u0633\u062a\u064a\u0648\u0627\u0631\u062a \u0645\u064a\u0644\u0631 \u060c \u0627\u0644\u0642\u0646\u0635\u0644 \u0627\u0644\u0641\u062e\u0631\u064a \u0647\u0627\u062a\u0641: (+1) 416-256-1947 \u0641\u0627\u0643\u0633: \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a: stumiller@rogers.com smiller@rogers.com \u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a: \u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15756,15945,15501,13033],"tags":[12951],"class_list":["post-139070","post","type-post","status-publish","format-standard","hentry","category-15756","category-15945","category-15501","category-13033","tag-12951"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/139070"}],"collection":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/comments?post=139070"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/139070\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/media?parent=139070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/categories?post=139070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/tags?post=139070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}