{"id":138909,"date":"2019-09-01T13:26:34","date_gmt":"2019-09-01T13:26:34","guid":{"rendered":"https:\/\/travelqa.com\/%d8%a7%d9%84%d8%b1%d8%b3%d9%88%d9%84-%d8%a7%d9%84%d8%b1%d8%b3%d9%88%d9%84%d9%8a-%d9%84%d9%84%d9%83%d8%b1%d8%b3%d9%8a-%d8%a7%d9%84%d8%b1%d8%b3%d9%88%d9%84%d9%8a-%d9%81%d9%8a-%d9%8a%d8%a7%d9%88%d9%86\/"},"modified":"2019-09-01T13:26:34","modified_gmt":"2019-09-01T13:26:34","slug":"%d8%a7%d9%84%d8%b1%d8%b3%d9%88%d9%84-%d8%a7%d9%84%d8%b1%d8%b3%d9%88%d9%84%d9%8a-%d9%84%d9%84%d9%83%d8%b1%d8%b3%d9%8a-%d8%a7%d9%84%d8%b1%d8%b3%d9%88%d9%84%d9%8a-%d9%81%d9%8a-%d9%8a%d8%a7%d9%88%d9%86","status":"publish","type":"post","link":"https:\/\/travelqa.com\/ar\/%d8%a7%d9%84%d8%b1%d8%b3%d9%88%d9%84-%d8%a7%d9%84%d8%b1%d8%b3%d9%88%d9%84%d9%8a-%d9%84%d9%84%d9%83%d8%b1%d8%b3%d9%8a-%d8%a7%d9%84%d8%b1%d8%b3%d9%88%d9%84%d9%8a-%d9%81%d9%8a-%d9%8a%d8%a7%d9%88%d9%86\/","title":{"rendered":"\u0627\u0644\u0631\u0633\u0648\u0644 \u0627\u0644\u0631\u0633\u0648\u0644\u064a \u0644\u0644\u0643\u0631\u0633\u064a \u0627\u0644\u0631\u0633\u0648\u0644\u064a \u0641\u064a \u064a\u0627\u0648\u0646\u062f\u064a \u060c \u0627\u0644\u0643\u0627\u0645\u064a\u0631\u0648\u0646"},"content":{"rendered":"<div id=\"trave-710941974\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>\u0627\u0644\u0643\u0631\u0633\u064a \u0627\u0644\u0631\u0633\u0648\u0644\u064a \u0627\u0644\u0631\u0633\u0648\u0644\u064a \u062a\u0641\u0627\u0635\u064a\u0644 \u0641\u064a \u064a\u0627\u0648\u0646\u062f\u064a \u060c \u0627\u0644\u0643\u0627\u0645\u064a\u0631\u0648\u0646<\/h3>\n<p><strong><br \/>\n\u0639\u0646\u0648\u0627\u0646:<\/strong><br \/>\n\u0634\u0627\u0631\u0639 \u0627\u0644\u0641\u0627\u062a\u064a\u0643\u0627\u0646 \u0628\u064a<br \/>\n.210<br \/>\n\u064a\u0627\u0648\u0646\u062f\u064a \u00a9<br \/>\n\u0627\u0644\u0643\u0627\u0645\u064a\u0631\u0648\u0646<br \/>\n<strong><br \/>\n\u0633\u0641\u064a\u0631:<\/strong><br \/>\n<strong>\u0647\u0627\u062a\u0641:<\/strong> (+237) 22 220-0475<br \/>\n(+237) 22 221-5073<br \/>\n<strong>\u0641\u0627\u0643\u0633:<\/strong> (+237) 22 220-7513<br \/>\n<strong>\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> nuntius.cam@gmail.com<br \/>\n<strong>\u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> <\/p>\n<p><strong>\u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/strong> <\/p>\n<div id=\"trave-3179907810\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0627\u0644\u0643\u0631\u0633\u064a \u0627\u0644\u0631\u0633\u0648\u0644\u064a \u0627\u0644\u0631\u0633\u0648\u0644\u064a \u062a\u0641\u0627\u0635\u064a\u0644 \u0641\u064a \u064a\u0627\u0648\u0646\u062f\u064a \u060c \u0627\u0644\u0643\u0627\u0645\u064a\u0631\u0648\u0646 \u0639\u0646\u0648\u0627\u0646: \u0634\u0627\u0631\u0639 \u0627\u0644\u0641\u0627\u062a\u064a\u0643\u0627\u0646 \u0628\u064a .210 \u064a\u0627\u0648\u0646\u062f\u064a \u00a9 \u0627\u0644\u0643\u0627\u0645\u064a\u0631\u0648\u0646 \u0633\u0641\u064a\u0631: \u0647\u0627\u062a\u0641: (+237) 22 220-0475 (+237) 22 221-5073 \u0641\u0627\u0643\u0633: (+237) 22 220-7513 \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a: nuntius.cam@gmail.com \u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a: \u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15942,13424,13125,13126],"tags":[13127],"class_list":["post-138909","post","type-post","status-publish","format-standard","hentry","category-15942","category-13424","category-13125","category-13126","tag-13127"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/138909"}],"collection":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/comments?post=138909"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/138909\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/media?parent=138909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/categories?post=138909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/tags?post=138909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}