{"id":138444,"date":"2019-09-01T13:22:31","date_gmt":"2019-09-01T13:22:31","guid":{"rendered":"https:\/\/travelqa.com\/%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%a7%d9%84%d9%86%d8%b1%d9%88%d9%8a%d8%ac-%d9%81%d9%8a-%d8%b3%d8%a7%d9%86%d8%aa%d9%88%d8%b3-%d8%a8%d8%a7%d9%84%d8%a8%d8%b1%d8%a7%d8%b2%d9%8a%d9%84\/"},"modified":"2019-09-01T13:22:31","modified_gmt":"2019-09-01T13:22:31","slug":"%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%a7%d9%84%d9%86%d8%b1%d9%88%d9%8a%d8%ac-%d9%81%d9%8a-%d8%b3%d8%a7%d9%86%d8%aa%d9%88%d8%b3-%d8%a8%d8%a7%d9%84%d8%a8%d8%b1%d8%a7%d8%b2%d9%8a%d9%84","status":"publish","type":"post","link":"https:\/\/travelqa.com\/ar\/%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%a7%d9%84%d9%86%d8%b1%d9%88%d9%8a%d8%ac-%d9%81%d9%8a-%d8%b3%d8%a7%d9%86%d8%aa%d9%88%d8%b3-%d8%a8%d8%a7%d9%84%d8%a8%d8%b1%d8%a7%d8%b2%d9%8a%d9%84\/","title":{"rendered":"\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u0646\u0631\u0648\u064a\u062c \u0641\u064a \u0633\u0627\u0646\u062a\u0648\u0633 \u0628\u0627\u0644\u0628\u0631\u0627\u0632\u064a\u0644"},"content":{"rendered":"<div id=\"trave-3660171685\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u0646\u0631\u0648\u064a\u062c\u064a\u0629 \u0641\u064a \u0633\u0627\u0646\u062a\u0648\u0633 \u060c \u0627\u0644\u0628\u0631\u0627\u0632\u064a\u0644<\/h3>\n<p><strong><br \/>\n\u0639\u0646\u0648\u0627\u0646:<\/strong><br \/>\nP\u00c3\u00a7a.Bar\u00c3 \u00a3 o do Rio Branco\u060c 14\u060c 4\u00c2\u00ba<br \/>\n11010-921 Santos &#8211; SP<br \/>\nBrazil<br \/>\n<strong><br \/>\n\u0633\u0641\u064a\u0631:<\/strong> \u0627\u0644\u0633\u064a\u062f \u063a\u0644\u064a\u0646 \u062c\u0648\u0631\u062f\u0648\u0646 \u0641\u064a\u0646\u062f\u0644\u064a \u060c \u0627\u0644\u0642\u0646\u0635\u0644 \u0627\u0644\u0641\u062e\u0631\u064a<br \/>\n<strong>\u0647\u0627\u062a\u0641:<\/strong> (+55) 13 3219 7373<br \/>\n<strong>\u0641\u0627\u0643\u0633:<\/strong> (+55) 13 3219 7944<br \/>\n<strong>\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> norconsulsto@grieg.com.br<br \/>\n<strong>\u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> <\/p>\n<p><strong>\u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/strong> 09.00 &#8211; 12.00 \u0648 13.00 &#8211; 17.00<\/p>\n<div id=\"trave-3086175435\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u0646\u0631\u0648\u064a\u062c\u064a\u0629 \u0641\u064a \u0633\u0627\u0646\u062a\u0648\u0633 \u060c \u0627\u0644\u0628\u0631\u0627\u0632\u064a\u0644 \u0639\u0646\u0648\u0627\u0646: P\u00c3\u00a7a.Bar\u00c3 \u00a3 o do Rio Branco\u060c 14\u060c 4\u00c2\u00ba 11010-921 Santos &#8211; SP Brazil \u0633\u0641\u064a\u0631: \u0627\u0644\u0633\u064a\u062f \u063a\u0644\u064a\u0646 \u062c\u0648\u0631\u062f\u0648\u0646 \u0641\u064a\u0646\u062f\u0644\u064a \u060c \u0627\u0644\u0642\u0646\u0635\u0644 \u0627\u0644\u0641\u062e\u0631\u064a \u0647\u0627\u062a\u0641: (+55) 13 3219 7373 \u0641\u0627\u0643\u0633: (+55) 13 3219 7944 \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a: norconsulsto@grieg.com.br \u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a: \u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644: 09.00 &#8211; 12.00 \u0648 13.00 &#8211; 17.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13298,15374,15879,13007],"tags":[12951],"class_list":["post-138444","post","type-post","status-publish","format-standard","hentry","category-13298","category-15374","category-15879","category-13007","tag-12951"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/138444"}],"collection":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/comments?post=138444"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/138444\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/media?parent=138444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/categories?post=138444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/tags?post=138444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}