{"id":137957,"date":"2019-09-01T13:18:52","date_gmt":"2019-09-01T13:18:52","guid":{"rendered":"https:\/\/travelqa.com\/%d8%a7%d9%84%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%a7%d9%84%d8%b9%d8%a7%d9%85%d8%a9-%d9%84%d8%a8%d9%86%d9%85%d8%a7-%d9%81%d9%8a-%d8%b3%d8%a7%d9%86%d8%aa%d9%88%d8%b3-%d8%a8%d8%a7%d9%84%d8%a8%d8%b1\/"},"modified":"2019-09-01T13:18:52","modified_gmt":"2019-09-01T13:18:52","slug":"%d8%a7%d9%84%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%a7%d9%84%d8%b9%d8%a7%d9%85%d8%a9-%d9%84%d8%a8%d9%86%d9%85%d8%a7-%d9%81%d9%8a-%d8%b3%d8%a7%d9%86%d8%aa%d9%88%d8%b3-%d8%a8%d8%a7%d9%84%d8%a8%d8%b1","status":"publish","type":"post","link":"https:\/\/travelqa.com\/ar\/%d8%a7%d9%84%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%a7%d9%84%d8%b9%d8%a7%d9%85%d8%a9-%d9%84%d8%a8%d9%86%d9%85%d8%a7-%d9%81%d9%8a-%d8%b3%d8%a7%d9%86%d8%aa%d9%88%d8%b3-%d8%a8%d8%a7%d9%84%d8%a8%d8%b1\/","title":{"rendered":"\u0627\u0644\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u0639\u0627\u0645\u0629 \u0644\u0628\u0646\u0645\u0627 \u0641\u064a \u0633\u0627\u0646\u062a\u0648\u0633 \u0628\u0627\u0644\u0628\u0631\u0627\u0632\u064a\u0644"},"content":{"rendered":"<div id=\"trave-3024211375\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>\u0627\u0644\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u0628\u0646\u0645\u064a\u0629 \u0627\u0644\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0639\u0627\u0645\u0629 \u0641\u064a \u0633\u0627\u0646\u062a\u0648\u0633 \u060c \u0627\u0644\u0628\u0631\u0627\u0632\u064a\u0644<\/h3>\n<p><strong><br \/>\n\u0639\u0646\u0648\u0627\u0646:<\/strong><br \/>\nAvenida Conselheiro Nebias \u060c 754 Conj.1914<br \/>\n\u0628\u0648\u0643\u0648\u064a\u0631\u0627\u0648<br \/>\nCEP 11045-002 \u0633\u0627\u0646\u062a\u0648\u0633 \/ SP<br \/>\n\u0627\u0644\u0628\u0631\u0627\u0632\u064a\u0644<br \/>\n<strong><br \/>\n\u0633\u0641\u064a\u0631:<\/strong> \u0628\u064a\u062f\u0631\u0648 \u0644\u0648\u064a\u062c\u064a \u0643\u0648\u0632\u0627\u0631\u064a\u0644\u064a \u0633\u064a\u0631\u0627\u0646\u0648 \u060c \u0627\u0644\u0642\u0646\u0635\u0644 \u0627\u0644\u0639\u0627\u0645<br \/>\n<strong>\u0647\u0627\u062a\u0641:<\/strong> (+55) 13-3221-3796<br \/>\n<strong>\u0641\u0627\u0643\u0633:<\/strong> (+55) 13-2138-3991<br \/>\n<strong>\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> consuladopanamasantos@hotmail.com<br \/>\n<strong>\u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> <\/p>\n<p><strong>\u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/strong> 11\u060c00-17\u060c00<\/p>\n<div id=\"trave-190098974\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0627\u0644\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u0628\u0646\u0645\u064a\u0629 \u0627\u0644\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0639\u0627\u0645\u0629 \u0641\u064a \u0633\u0627\u0646\u062a\u0648\u0633 \u060c \u0627\u0644\u0628\u0631\u0627\u0632\u064a\u0644 \u0639\u0646\u0648\u0627\u0646: Avenida Conselheiro Nebias \u060c 754 Conj.1914 \u0628\u0648\u0643\u0648\u064a\u0631\u0627\u0648 CEP 11045-002 \u0633\u0627\u0646\u062a\u0648\u0633 \/ SP \u0627\u0644\u0628\u0631\u0627\u0632\u064a\u0644 \u0633\u0641\u064a\u0631: \u0628\u064a\u062f\u0631\u0648 \u0644\u0648\u064a\u062c\u064a \u0643\u0648\u0632\u0627\u0631\u064a\u0644\u064a \u0633\u064a\u0631\u0627\u0646\u0648 \u060c \u0627\u0644\u0642\u0646\u0635\u0644 \u0627\u0644\u0639\u0627\u0645 \u0647\u0627\u062a\u0641: (+55) 13-3221-3796 \u0641\u0627\u0643\u0633: (+55) 13-2138-3991 \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a: consuladopanamasantos@hotmail.com \u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a: \u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644: 11\u060c00-17\u060c00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13298,15492,15880,15453],"tags":[12962],"class_list":["post-137957","post","type-post","status-publish","format-standard","hentry","category-13298","category-15492","category-15880","category-15453","tag-12962"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/137957"}],"collection":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/comments?post=137957"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/137957\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/media?parent=137957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/categories?post=137957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/tags?post=137957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}