{"id":137252,"date":"2019-09-01T13:04:31","date_gmt":"2019-09-01T13:04:31","guid":{"rendered":"https:\/\/travelqa.com\/%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%a7%d9%84%d9%86%d9%85%d8%b3%d8%a7-%d9%81%d9%8a-%d9%84%d9%8a%d9%8a%d8%ac-%d8%8c-%d8%a8%d9%84%d8%ac%d9%8a%d9%83%d8%a7\/"},"modified":"2019-09-01T13:04:31","modified_gmt":"2019-09-01T13:04:31","slug":"%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%a7%d9%84%d9%86%d9%85%d8%b3%d8%a7-%d9%81%d9%8a-%d9%84%d9%8a%d9%8a%d8%ac-%d8%8c-%d8%a8%d9%84%d8%ac%d9%8a%d9%83%d8%a7","status":"publish","type":"post","link":"https:\/\/travelqa.com\/ar\/%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%a7%d9%84%d9%86%d9%85%d8%b3%d8%a7-%d9%81%d9%8a-%d9%84%d9%8a%d9%8a%d8%ac-%d8%8c-%d8%a8%d9%84%d8%ac%d9%8a%d9%83%d8%a7\/","title":{"rendered":"\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u0646\u0645\u0633\u0627 \u0641\u064a \u0644\u064a\u064a\u062c \u060c \u0628\u0644\u062c\u064a\u0643\u0627"},"content":{"rendered":"<div id=\"trave-1253996385\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u0646\u0645\u0633\u0627\u0648\u064a\u0629 \u0641\u064a \u0644\u064a\u064a\u062c \u060c \u0628\u0644\u062c\u064a\u0643\u0627<\/h3>\n<p><strong><br \/>\n\u0639\u0646\u0648\u0627\u0646:<\/strong><br \/>\nRue Vacale 5<br \/>\n4140 Sprimont<br \/>\nBelgium<br \/>\n<strong><br \/>\n\u0633\u0641\u064a\u0631:<\/strong> \u062c\u0627\u0643 \u062c\u0627\u0646 \u0627\u0644\u0643\u0633\u064a\u0633 \u062a\u0648\u0645\u0627\u0633 \u060c \u0627\u0644\u0642\u0646\u0635\u0644 \u0627\u0644\u0641\u062e\u0631\u064a<br \/>\n<strong>\u0647\u0627\u062a\u0641:<\/strong> (+32) 4 384 01 11<br \/>\n<strong>\u0641\u0627\u0643\u0633:<\/strong> (+32) 4 382 16 96<br \/>\n<strong>\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> j.thomas@soudobeam.be<br \/>\n<strong>\u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> <\/p>\n<p><strong>\u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/strong> \u0627\u0644\u0627\u062b\u0646\u064a\u0646: 09.00-12.00<\/p>\n<div id=\"trave-1382765747\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u0646\u0645\u0633\u0627\u0648\u064a\u0629 \u0641\u064a \u0644\u064a\u064a\u062c \u060c \u0628\u0644\u062c\u064a\u0643\u0627 \u0639\u0646\u0648\u0627\u0646: Rue Vacale 5 4140 Sprimont Belgium \u0633\u0641\u064a\u0631: \u062c\u0627\u0643 \u062c\u0627\u0646 \u0627\u0644\u0643\u0633\u064a\u0633 \u062a\u0648\u0645\u0627\u0633 \u060c \u0627\u0644\u0642\u0646\u0635\u0644 \u0627\u0644\u0641\u062e\u0631\u064a \u0647\u0627\u062a\u0641: (+32) 4 384 01 11 \u0641\u0627\u0643\u0633: (+32) 4 382 16 96 \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a: j.thomas@soudobeam.be \u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a: \u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644: \u0627\u0644\u0627\u062b\u0646\u064a\u0646: 09.00-12.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13036,15747,13034,12952],"tags":[12951],"class_list":["post-137252","post","type-post","status-publish","format-standard","hentry","category-13036","category-15747","category-13034","category-12952","tag-12951"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/137252"}],"collection":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/comments?post=137252"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/137252\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/media?parent=137252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/categories?post=137252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/tags?post=137252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}