{"id":136479,"date":"2019-09-01T12:51:42","date_gmt":"2019-09-01T12:51:42","guid":{"rendered":"https:\/\/travelqa.com\/%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%ac%d9%85%d9%87%d9%88%d8%b1%d9%8a%d8%a9-%d8%a7%d9%84%d8%aa%d8%b4%d9%8a%d9%83-%d9%81%d9%8a-%d8%b3%d8%a7%d9%84%d8%b2%d8%a8%d9%88%d8%b1%d8%ba-%d8%a8%d8%a7%d9%84\/"},"modified":"2019-09-01T12:51:42","modified_gmt":"2019-09-01T12:51:42","slug":"%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%ac%d9%85%d9%87%d9%88%d8%b1%d9%8a%d8%a9-%d8%a7%d9%84%d8%aa%d8%b4%d9%8a%d9%83-%d9%81%d9%8a-%d8%b3%d8%a7%d9%84%d8%b2%d8%a8%d9%88%d8%b1%d8%ba-%d8%a8%d8%a7%d9%84","status":"publish","type":"post","link":"https:\/\/travelqa.com\/ar\/%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d8%ac%d9%85%d9%87%d9%88%d8%b1%d9%8a%d8%a9-%d8%a7%d9%84%d8%aa%d8%b4%d9%8a%d9%83-%d9%81%d9%8a-%d8%b3%d8%a7%d9%84%d8%b2%d8%a8%d9%88%d8%b1%d8%ba-%d8%a8%d8%a7%d9%84\/","title":{"rendered":"\u0642\u0646\u0635\u0644\u064a\u0629 \u062c\u0645\u0647\u0648\u0631\u064a\u0629 \u0627\u0644\u062a\u0634\u064a\u0643 \u0641\u064a \u0633\u0627\u0644\u0632\u0628\u0648\u0631\u063a \u0628\u0627\u0644\u0646\u0645\u0633\u0627"},"content":{"rendered":"<div id=\"trave-2314544219\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u062a\u0634\u064a\u0643\u064a\u0629 \u0641\u064a \u0633\u0627\u0644\u0632\u0628\u0648\u0631\u062c \u060c \u0627\u0644\u0646\u0645\u0633\u0627<\/h3>\n<p><strong><br \/>\n\u0639\u0646\u0648\u0627\u0646:<\/strong><br \/>\nBayerhamerstrasse 14c<br \/>\n5020 \u0633\u0627\u0644\u0632\u0628\u0648\u0631\u063a<br \/>\n\u0627\u0644\u0646\u0645\u0633\u0627<br \/>\n<strong><br \/>\n\u0633\u0641\u064a\u0631:<\/strong> \u0643\u0644\u064a\u0645\u0646\u0633 \u0634\u0648\u064a\u0643\u0627 \u060c \u0627\u0644\u0642\u0646\u0635\u0644 \u0627\u0644\u0641\u062e\u0631\u064a<br \/>\n<strong>\u0647\u0627\u062a\u0641:<\/strong> (+43) 662 879 624<br \/>\n<strong>\u0641\u0627\u0643\u0633:<\/strong> (+43) 662 815 160 80<br \/>\n<strong>\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> salzburg@honorary.mzv.cz<br \/>\n<strong>\u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> <\/p>\n<p><strong>\u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/strong> \u0627\u0644\u062b\u0644\u0627\u062b\u0627\u0621: 14.00 &#8211; 17.00<\/p>\n<div id=\"trave-1727994121\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u062a\u0634\u064a\u0643\u064a\u0629 \u0641\u064a \u0633\u0627\u0644\u0632\u0628\u0648\u0631\u062c \u060c \u0627\u0644\u0646\u0645\u0633\u0627 \u0639\u0646\u0648\u0627\u0646: Bayerhamerstrasse 14c 5020 \u0633\u0627\u0644\u0632\u0628\u0648\u0631\u063a \u0627\u0644\u0646\u0645\u0633\u0627 \u0633\u0641\u064a\u0631: \u0643\u0644\u064a\u0645\u0646\u0633 \u0634\u0648\u064a\u0643\u0627 \u060c \u0627\u0644\u0642\u0646\u0635\u0644 \u0627\u0644\u0641\u062e\u0631\u064a \u0647\u0627\u062a\u0641: (+43) 662 879 624 \u0641\u0627\u0643\u0633: (+43) 662 815 160 80 \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a: salzburg@honorary.mzv.cz \u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a: \u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644: \u0627\u0644\u062b\u0644\u0627\u062b\u0627\u0621: 14.00 &#8211; 17.00<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13459,15646,13034,12965],"tags":[12951],"class_list":["post-136479","post","type-post","status-publish","format-standard","hentry","category-13459","category-15646","category-13034","category-12965","tag-12951"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/136479"}],"collection":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/comments?post=136479"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/136479\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/media?parent=136479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/categories?post=136479"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/tags?post=136479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}