{"id":136377,"date":"2019-09-01T12:49:18","date_gmt":"2019-09-01T12:49:18","guid":{"rendered":"https:\/\/travelqa.com\/%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d9%84%d8%a7%d8%aa%d9%81%d9%8a%d8%a7-%d9%81%d9%8a-%d9%85%d9%84%d8%a8%d9%88%d8%b1%d9%86-%d8%8c-%d8%a3%d8%b3%d8%aa%d8%b1%d8%a7%d9%84%d9%8a%d8%a7\/"},"modified":"2019-09-01T12:49:18","modified_gmt":"2019-09-01T12:49:18","slug":"%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d9%84%d8%a7%d8%aa%d9%81%d9%8a%d8%a7-%d9%81%d9%8a-%d9%85%d9%84%d8%a8%d9%88%d8%b1%d9%86-%d8%8c-%d8%a3%d8%b3%d8%aa%d8%b1%d8%a7%d9%84%d9%8a%d8%a7","status":"publish","type":"post","link":"https:\/\/travelqa.com\/ar\/%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d9%84%d8%a7%d8%aa%d9%81%d9%8a%d8%a7-%d9%81%d9%8a-%d9%85%d9%84%d8%a8%d9%88%d8%b1%d9%86-%d8%8c-%d8%a3%d8%b3%d8%aa%d8%b1%d8%a7%d9%84%d9%8a%d8%a7\/","title":{"rendered":"\u0642\u0646\u0635\u0644\u064a\u0629 \u0644\u0627\u062a\u0641\u064a\u0627 \u0641\u064a \u0645\u0644\u0628\u0648\u0631\u0646 \u060c \u0623\u0633\u062a\u0631\u0627\u0644\u064a\u0627"},"content":{"rendered":"<div id=\"trave-585224973\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u0644\u0627\u062a\u0641\u064a\u0629 \u0641\u064a \u0645\u0644\u0628\u0648\u0631\u0646 \u060c \u0623\u0633\u062a\u0631\u0627\u0644\u064a\u0627<\/h3>\n<p><strong><br \/>\n\u0639\u0646\u0648\u0627\u0646:<\/strong><br \/>\n3\/30 Lansell Road<br \/>\nToorak Vic 3142<br \/>\nPO Box 23<br \/>\nKew Vic\u060c VIC 3101<br \/>\nAustralia<br \/>\n<strong><br \/>\n\u0633\u0641\u064a\u0631:<\/strong> \u0627\u0644\u0633\u064a\u062f \u062c\u0627\u0646\u064a\u0633 \u0631\u0648\u0628\u0631\u062a\u0633 \u062f\u064a\u0644\u064a\u0646\u0632 \u060c \u0627\u0644\u0642\u0646\u0635\u0644 \u0627\u0644\u0641\u062e\u0631\u064a<br \/>\n<strong>\u0647\u0627\u062a\u0641:<\/strong> (+61) 3 982 40707<br \/>\n<strong>\u0641\u0627\u0643\u0633:<\/strong><br \/>\n<strong>\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> latcon@ozemail.com.au<br \/>\n<strong>\u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> <\/p>\n<p><strong>\u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/strong> \u0628\u0627\u0644\u0645\u064a\u0639\u0627\u062f<\/p>\n<div id=\"trave-3468747349\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0642\u0646\u0635\u0644\u064a\u0629 \u0627\u0644\u0644\u0627\u062a\u0641\u064a\u0629 \u0641\u064a \u0645\u0644\u0628\u0648\u0631\u0646 \u060c \u0623\u0633\u062a\u0631\u0627\u0644\u064a\u0627 \u0639\u0646\u0648\u0627\u0646: 3\/30 Lansell Road Toorak Vic 3142 PO Box 23 Kew Vic\u060c VIC 3101 Australia \u0633\u0641\u064a\u0631: \u0627\u0644\u0633\u064a\u062f \u062c\u0627\u0646\u064a\u0633 \u0631\u0648\u0628\u0631\u062a\u0633 \u062f\u064a\u0644\u064a\u0646\u0632 \u060c \u0627\u0644\u0642\u0646\u0635\u0644 \u0627\u0644\u0641\u062e\u0631\u064a \u0647\u0627\u062a\u0641: (+61) 3 982 40707 \u0641\u0627\u0643\u0633: \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a: latcon@ozemail.com.au \u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a: \u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644: \u0628\u0627\u0644\u0645\u064a\u0639\u0627\u062f<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12963,13109,15497,13108],"tags":[12951],"class_list":["post-136377","post","type-post","status-publish","format-standard","hentry","category-12963","category-13109","category-15497","category-13108","tag-12951"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/136377"}],"collection":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/comments?post=136377"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/136377\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/media?parent=136377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/categories?post=136377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/tags?post=136377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}