{"id":136358,"date":"2019-09-01T12:49:06","date_gmt":"2019-09-01T12:49:06","guid":{"rendered":"https:\/\/travelqa.com\/%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d9%83%d9%88%d8%b3%d9%88%d9%81%d9%88-%d9%81%d9%8a-%d8%a3%d8%af%d9%8a%d9%84%d9%8a%d8%af-%d8%8c-%d8%a3%d8%b3%d8%aa%d8%b1%d8%a7%d9%84%d9%8a%d8%a7\/"},"modified":"2019-09-01T12:49:06","modified_gmt":"2019-09-01T12:49:06","slug":"%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d9%83%d9%88%d8%b3%d9%88%d9%81%d9%88-%d9%81%d9%8a-%d8%a3%d8%af%d9%8a%d9%84%d9%8a%d8%af-%d8%8c-%d8%a3%d8%b3%d8%aa%d8%b1%d8%a7%d9%84%d9%8a%d8%a7","status":"publish","type":"post","link":"https:\/\/travelqa.com\/ar\/%d9%82%d9%86%d8%b5%d9%84%d9%8a%d8%a9-%d9%83%d9%88%d8%b3%d9%88%d9%81%d9%88-%d9%81%d9%8a-%d8%a3%d8%af%d9%8a%d9%84%d9%8a%d8%af-%d8%8c-%d8%a3%d8%b3%d8%aa%d8%b1%d8%a7%d9%84%d9%8a%d8%a7\/","title":{"rendered":"\u0642\u0646\u0635\u0644\u064a\u0629 \u0643\u0648\u0633\u0648\u0641\u0648 \u0641\u064a \u0623\u062f\u064a\u0644\u064a\u062f \u060c \u0623\u0633\u062a\u0631\u0627\u0644\u064a\u0627"},"content":{"rendered":"<div id=\"trave-3254431037\" class=\"trave-before-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><h3>\u062a\u0641\u0627\u0635\u064a\u0644 \u0642\u0646\u0635\u0644\u064a\u0629 \u0643\u0648\u0633\u0648\u0641\u0648 \u0641\u064a \u0623\u062f\u064a\u0644\u064a\u062f \u060c \u0623\u0633\u062a\u0631\u0627\u0644\u064a\u0627<\/h3>\n<p><strong><br \/>\n\u0639\u0646\u0648\u0627\u0646:<\/strong><br \/>\nGPO Box 2465<br \/>\nAdelaide\u060c SA 5001 5001<br \/>\nAustralia<br \/>\n<strong><br \/>\n\u0633\u0641\u064a\u0631:<\/strong> \u0627\u0644\u0633\u064a\u062f \u0631\u0624\u0648\u0641 \u0633\u0648\u0644\u064a\u0648 \u060c \u0627\u0644\u0642\u0646\u0635\u0644 \u0627\u0644\u0641\u062e\u0631\u064a<br \/>\n<strong>\u0647\u0627\u062a\u0641:<\/strong> (+61) 419 863 286<br \/>\n(+61) (8) 8204 0221 \/ (8) 8226 1947<br \/>\n<strong>\u0641\u0627\u0643\u0633:<\/strong><br \/>\n<strong>\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> ralf.soulio@sa.gov.au<br \/>\n<strong>\u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a:<\/strong> <\/p>\n<p><strong>\u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/strong> <\/p>\n<div id=\"trave-3006201457\" class=\"trave-after-content trave-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8186974851578609\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-8186974851578609\" \ndata-ad-slot=\"4306320211\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u062a\u0641\u0627\u0635\u064a\u0644 \u0642\u0646\u0635\u0644\u064a\u0629 \u0643\u0648\u0633\u0648\u0641\u0648 \u0641\u064a \u0623\u062f\u064a\u0644\u064a\u062f \u060c \u0623\u0633\u062a\u0631\u0627\u0644\u064a\u0627 \u0639\u0646\u0648\u0627\u0646: GPO Box 2465 Adelaide\u060c SA 5001 5001 Australia \u0633\u0641\u064a\u0631: \u0627\u0644\u0633\u064a\u062f \u0631\u0624\u0648\u0641 \u0633\u0648\u0644\u064a\u0648 \u060c \u0627\u0644\u0642\u0646\u0635\u0644 \u0627\u0644\u0641\u062e\u0631\u064a \u0647\u0627\u062a\u0641: (+61) 419 863 286 (+61) (8) 8204 0221 \/ (8) 8226 1947 \u0641\u0627\u0643\u0633: \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a: ralf.soulio@sa.gov.au \u0645\u0648\u0642\u0639 \u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a: \u0633\u0627\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12963,15497,15628,13211],"tags":[12951],"class_list":["post-136358","post","type-post","status-publish","format-standard","hentry","category-12963","category-15497","category-15628","category-13211","tag-12951"],"_links":{"self":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/136358"}],"collection":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/comments?post=136358"}],"version-history":[{"count":0,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/posts\/136358\/revisions"}],"wp:attachment":[{"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/media?parent=136358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/categories?post=136358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travelqa.com\/ar\/wp-json\/wp\/v2\/tags?post=136358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}